[{"id":82975,"date":"2026-05-11T09:27:43","date_gmt":"2026-05-11T09:27:43","guid":{"rendered":"https:\/\/kongskilde-industries.com\/the-missing-link-in-plastics-production-efficiency\/"},"modified":"2026-05-11T09:28:19","modified_gmt":"2026-05-11T09:28:19","slug":"the-missing-link-in-plastics-production-efficiency","status":"publish","type":"post","link":"https:\/\/kongskilde-industries.com\/es\/the-missing-link-in-plastics-production-efficiency\/","title":{"rendered":"El eslab\u00f3n perdido en la eficiencia de la producci\u00f3n de pl\u00e1sticos"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull has-parallax\" style=\"margin-top:0;margin-bottom:0;min-height:300px;aspect-ratio:unset;\"><div class=\"wp-block-cover__image-background wp-image-89198 size-full has-parallax\" style=\"background-position:50% 50%;background-image:url(https:\/\/kongskilde-industries.com\/industrial\/wp-content\/uploads\/sites\/3\/Various-plastic-pellets_lids_bags_trim_web.jpg)\"><\/div><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p><\/p>\n<\/div><\/div>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-columns is-style-xl-gutter is-layout-flex wp-container-core-columns-is-layout-f1641cd0 wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h2 class=\"wp-block-heading has-palette-brand-1-color has-text-color has-link-color has-medium-font-size wp-elements-a5f7b2dbd77e5ea7de300d99134dc1ae\" id=\"h-how-smarter-material-handling-improves-uptime-efficiency-and-roi\" style=\"text-transform:none\"><strong>C\u00f3mo una manipulaci\u00f3n de materiales m\u00e1s inteligente mejora el tiempo de actividad, la eficiencia y el retorno de la inversi\u00f3n<\/strong><\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>En la fabricaci\u00f3n de pl\u00e1sticos, el aumento de la producci\u00f3n se asocia a menudo con la inversi\u00f3n en nuevas m\u00e1quinas. Sin embargo, muchas ganancias de producci\u00f3n no proceden \u00fanicamente de a\u00f1adir equipos. En su lugar, pueden provenir de mejorar la forma en que los materiales se mueven a trav\u00e9s del proceso de producci\u00f3n.  <\/p>\n\n\n\n<p>La forma en que los materiales se mueven a trav\u00e9s de un proceso de producci\u00f3n rara vez recibe la misma atenci\u00f3n que el equipo de producci\u00f3n. Sin embargo, el transporte determina a menudo que una l\u00ednea de producci\u00f3n funcione con eficacia o sufra interrupciones. <\/p>\n\n\n\n<p>Cuando los materiales se mueven de forma fluida y predecible entre los procesos, las l\u00edneas de producci\u00f3n funcionan de forma m\u00e1s consistente, se reducen los tiempos de inactividad y los fabricantes pueden obtener m\u00e1s valor de los equipos que ya tienen.<\/p>\n\n\n\n<p>En toda la industria del pl\u00e1stico, los fabricantes est\u00e1n sometidos a una presi\u00f3n cada vez mayor para maximizar la eficiencia. Los costes de las materias primas fluct\u00faan, los objetivos de sostenibilidad son cada vez m\u00e1s ambiciosos y la mano de obra cualificada puede ser dif\u00edcil de encontrar. <\/p>\n\n\n\n<p>En estas condiciones, la mejora del flujo operativo puede proporcionar importantes beneficios sin requerir grandes inversiones de capital.<\/p>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-columns is-style-xl-gutter is-layout-flex wp-container-core-columns-is-layout-f1641cd0 wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h2 class=\"wp-block-heading has-palette-brand-1-color has-text-color has-link-color has-medium-font-size wp-elements-974463c353ae64f34f7cadc8d0c3750c\" id=\"h-do-not-let-poor-flow-disrupt-production\" style=\"text-transform:none\"><strong>No deje que un flujo deficiente interrumpa la producci\u00f3n<\/strong><\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Los materiales deben suministrarse de forma fiable a las m\u00e1quinas, el material reciclado debe volver al proceso y los residuos deben eliminarse sin interrumpir la producci\u00f3n.<\/p>\n\n\n\n<p>Los residuos de la producci\u00f3n, como los recortes, los recortes, el reafilado o la rebaba, siguen conteniendo material valioso. Si se gestionan con eficacia, estos materiales pueden procesarse y reintroducirse en el flujo de producci\u00f3n. <\/p>\n\n\n\n<p>En muchas instalaciones, sin embargo, la manipulaci\u00f3n de residuos no suele estar totalmente integrada en el proceso de producci\u00f3n. En su lugar, se trata como una tarea separada que requiere que los operarios retiren peri\u00f3dicamente la chatarra, la transporten para su procesamiento y la preparen para su reciclaje. Estos pasos adicionales pueden introducir retrasos e interrumpir el flujo de producci\u00f3n.  <\/p>\n\n\n\n<p>\u00ab<em>Muchas f\u00e1bricas siguen gestionando los residuos manualmente\u00bb, <\/em>explica el CCO de Kongskilde, Greg Bacon. <em>\u00abAlguien lo recoge, lo traslada, lo procesa y, finalmente, lo devuelve a la producci\u00f3n. El transporte autom\u00e1tico elimina esas interrupciones y mantiene la l\u00ednea de producci\u00f3n en funcionamiento continuo.\u00bb<\/em><\/p>\n\n\n\n<p>Al reducir la manipulaci\u00f3n manual y permitir un transporte automatizado m\u00e1s inteligente, los fabricantes pueden evitar que los residuos se conviertan en un cuello de botella que ralentice todo el proceso.<\/p>\n<\/div>\n<\/div>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-cover alignfull has-parallax is-style-no-space wp-duotone-varpresetduotoneblack-and-quaternary-1\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0;min-height:150px;aspect-ratio:unset;\"><div class=\"wp-block-cover__image-background wp-image-89198 size-full has-parallax\" style=\"background-position:50% 50%;background-image:url(https:\/\/kongskilde-industries.com\/industrial\/wp-content\/uploads\/sites\/3\/Various-plastic-pellets_lids_bags_trim_web.jpg)\"><\/div><span aria-hidden=\"true\" class=\"wp-block-cover__background has-palette-brand-1-background-color has-background-dim-30 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p><\/p>\n<\/div><\/div>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-columns is-style-xl-gutter is-layout-flex wp-container-core-columns-is-layout-2d85a6ef wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--80);margin-bottom:var(--wp--preset--spacing--80)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h2 class=\"wp-block-heading has-palette-brand-1-color has-text-color has-link-color has-medium-font-size wp-elements-2f9feb06ba100a51a330b04ca31cdb97\" id=\"h-closing-the-loop-on-production-waste\" style=\"text-transform:none\"><strong>Cerrar el c\u00edrculo de los residuos de producci\u00f3n<\/strong><\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Los entornos de producci\u00f3n modernos se centran cada vez m\u00e1s en recuperar y reutilizar los materiales lo antes posible. Cuando los residuos pasan directamente de una m\u00e1quina de producci\u00f3n a la siguiente fase de procesamiento, como la trituraci\u00f3n, el desempolvado o el reciclado, se convierten en parte de un bucle continuo en lugar de un proceso independiente. <\/p>\n\n\n\n<p><em>\u00abLa verdadera ventaja es cuando los residuos pueden salir directamente de la m\u00e1quina, procesarse por el camino y volver directamente al flujo de producci\u00f3n sin que nadie los toque\u00bb,<\/em> explica Greg Bacon.<\/p>\n\n\n\n<p>Un enfoque de bucle cerrado permite reutilizar el valioso material de forma r\u00e1pida y constante. Esto reduce la dependencia del material virgen a la vez que mantiene unas condiciones de producci\u00f3n estables. <\/p>\n\n\n\n<p>Y lo que es igual de importante, la manipulaci\u00f3n continua de residuos evita la acumulaci\u00f3n alrededor de las m\u00e1quinas, que de otro modo podr\u00eda provocar interrupciones o ralentizaciones en la planta de producci\u00f3n. Al eliminar los recortes, desechos o reafilados directamente del proceso, los fabricantes pueden reducir significativamente la necesidad de limpieza manual. Esto ayuda a mantener las \u00e1reas de producci\u00f3n m\u00e1s seguras y organizadas, al tiempo que permite a los operarios centrarse en tareas de mayor valor. Con el tiempo, la reducci\u00f3n de la manipulaci\u00f3n manual de residuos y de la limpieza rutinaria puede favorecer una mayor automatizaci\u00f3n de la f\u00e1brica, reducir las necesidades de mano de obra y contribuir a mejorar la eficacia operativa general.   <\/p>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-columns is-style-xl-gutter is-layout-flex wp-container-core-columns-is-layout-2d85a6ef wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--80);margin-bottom:var(--wp--preset--spacing--80)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h2 class=\"wp-block-heading has-palette-brand-1-color has-text-color has-link-color has-medium-font-size wp-elements-9d2f57d9a3cdb317adafe1145513a58a\" id=\"h-small-efficiency-gains-significant-financial-impact\" style=\"text-transform:none\"><strong>Peque\u00f1as ganancias de eficiencia, impacto financiero significativo<\/strong><\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Mejorar el rendimiento de una l\u00ednea de producci\u00f3n existente suele proporcionar un mayor retorno de la inversi\u00f3n que ampliar la capacidad. De hecho, los estudios demuestran que las actividades de manipulaci\u00f3n de materiales pueden representar entre el 15% y el 70% de los costes totales de fabricaci\u00f3n.\u00b9 <\/p>\n\n\n\n<p>Por eso, las peque\u00f1as ineficiencias operativas, como la acumulaci\u00f3n de residuos, los retrasos en la manipulaci\u00f3n manual o los procesos de reciclado incoherentes, pueden erosionar gradualmente la productividad. Con el tiempo, estas interrupciones se traducen en horas de producci\u00f3n perdidas, mayores necesidades de mano de obra y un aumento de los costes de material. <\/p>\n\n\n\n<p>A menudo, el problema subyacente no es la m\u00e1quina en s\u00ed, sino el proceso que la rodea.<\/p>\n\n\n\n<p>Por ejemplo, la trituraci\u00f3n de residuos pl\u00e1sticos puede producir part\u00edculas finas y polvo. Si estas part\u00edculas permanecen en el flujo de reciclado, pueden atascar los equipos posteriores, como las extrusoras. Para eliminar esos atascos es necesario detener la producci\u00f3n, limpiar el sistema y volver a poner en marcha la l\u00ednea. Interrupciones que pueden sumarse r\u00e1pidamente en el transcurso de una semana.   <\/p>\n\n\n\n<p>\u00ab<em>Cuando el material que vuelve al proceso est\u00e1 limpio y preparado adecuadamente, la producci\u00f3n funciona de forma consistente\u00bb,<\/em> afirma Greg Bacon. <em>\u00abEso crea efectos domin\u00f3 en toda la l\u00ednea de producci\u00f3n\u00bb.<\/em><\/p>\n\n\n\n<p>En la producci\u00f3n de pl\u00e1stico, eliminar las impurezas del material reciclado es fundamental, ya que la contaminaci\u00f3n puede afectar a la calidad del material final y, a menudo, provocar decoloraci\u00f3n. Cuando el material reciclado se prepara adecuadamente antes de reintroducirlo en el proceso, se ayuda a mantener un rendimiento constante, al tiempo que se protege el equipo de un desgaste y un tiempo de inactividad innecesarios. <\/p>\n<\/div>\n<\/div>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-cover alignfull has-parallax is-style-no-space wp-duotone-varpresetduotoneblack-and-quaternary-2\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0;min-height:150px;aspect-ratio:unset;\"><div class=\"wp-block-cover__image-background wp-image-89198 size-full has-parallax\" style=\"background-position:50% 50%;background-image:url(https:\/\/kongskilde-industries.com\/industrial\/wp-content\/uploads\/sites\/3\/Various-plastic-pellets_lids_bags_trim_web.jpg)\"><\/div><span aria-hidden=\"true\" class=\"wp-block-cover__background has-palette-brand-1-background-color has-background-dim-30 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p><\/p>\n<\/div><\/div>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-columns is-style-xl-gutter is-layout-flex wp-container-core-columns-is-layout-2d85a6ef wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--80);margin-bottom:var(--wp--preset--spacing--80)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h2 class=\"wp-block-heading has-palette-brand-1-color has-text-color has-link-color has-medium-font-size wp-elements-873b3ed16b2b5ffd6ba89f087405bc37\" id=\"h-automation-supports-uptime-and-workforce-efficiency\" style=\"text-transform:none\"><strong>La automatizaci\u00f3n favorece el tiempo de actividad y la eficiencia de la mano de obra<\/strong><\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Un flujo de material fiable tambi\u00e9n desempe\u00f1a un papel importante a la hora de maximizar el tiempo de funcionamiento de la m\u00e1quina.<\/p>\n\n\n\n<p>Cuando la retirada de residuos y el reciclaje se gestionan autom\u00e1ticamente, las m\u00e1quinas ya no necesitan detenerse mientras los operarios retiran la chatarra o los contenedores vac\u00edos. En su lugar, el material se transporta lejos de la m\u00e1quina y se procesa mientras contin\u00faa la producci\u00f3n. <\/p>\n\n\n\n<p>Esto permite que los equipos funcionen durante m\u00e1s tiempo sin interrupciones, al tiempo que se mantiene un entorno de producci\u00f3n m\u00e1s limpio y organizado.<\/p>\n\n\n\n<p>La automatizaci\u00f3n tambi\u00e9n puede reducir el tiempo que los trabajadores dedican a tareas repetitivas como el transporte de chatarra o la gesti\u00f3n de los contenedores de residuos. En su lugar, los empleados pueden centrarse en supervisar los equipos, mantener los est\u00e1ndares de calidad y mejorar los procesos de producci\u00f3n. <\/p>\n\n\n\n<p>En la pr\u00e1ctica, la manipulaci\u00f3n automatizada se traduce en resultados cuantificables. Una instalaci\u00f3n consigui\u00f3 un retorno de la inversi\u00f3n de 12 meses automatizando el transporte de residuos, al tiempo que reduc\u00eda los costes de mano de obra en un 30% y eliminaba la necesidad de manipular con carretillas elevadoras dentro de la zona de producci\u00f3n.\u00b2 <\/p>\n\n\n\n<p>En una industria en la que cada vez es m\u00e1s dif\u00edcil encontrar operarios con experiencia, este cambio ayuda a los fabricantes a utilizar su mano de obra de forma m\u00e1s eficaz.<\/p>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-columns is-style-xl-gutter is-layout-flex wp-container-core-columns-is-layout-2d85a6ef wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--80);margin-bottom:var(--wp--preset--spacing--80)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h2 class=\"wp-block-heading has-palette-brand-1-color has-text-color has-link-color has-medium-font-size wp-elements-bbda6b610806b2ae35d1c5b3a834346e\" id=\"h-reducing-risk-in-material-transfer\" style=\"text-transform:none\"><strong><strong>Reducir el riesgo en la transferencia de material<\/strong><\/strong><\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Otro factor importante es c\u00f3mo se transportan los materiales a trav\u00e9s del sistema o dentro de las instalaciones.<\/p>\n\n\n\n<p>A menudo, los residuos y el material reciclado se recogen en contenedores o se trasladan entre procesos mediante manipulaci\u00f3n manual o equipos mec\u00e1nicos. Aunque estos m\u00e9todos pueden ser eficaces, implican puntos de contacto adicionales y dejan m\u00e1s oportunidades para el polvo, la contaminaci\u00f3n o la p\u00e9rdida de material durante el traslado. <\/p>\n\n\n\n<p>El transporte neum\u00e1tico ofrece una forma m\u00e1s contenida de mover el material a trav\u00e9s de la producci\u00f3n. Al transportar el material a trav\u00e9s de tuber\u00edas cerradas, ayuda a mantener el polvo dentro del sistema, reduciendo el riesgo de contaminaci\u00f3n y limitando la limpieza en la planta de producci\u00f3n. <\/p>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-columns is-style-xl-gutter is-layout-flex wp-container-core-columns-is-layout-2d85a6ef wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--80);margin-bottom:var(--wp--preset--spacing--80)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h2 class=\"wp-block-heading has-palette-brand-1-color has-text-color has-link-color has-medium-font-size wp-elements-b2bac3639a830a8527da2525bd70984e\" id=\"h-getting-more-from-existing-production-lines\" style=\"text-transform:none\"><strong><strong>Obtener m\u00e1s de las l\u00edneas de producci\u00f3n existentes<\/strong><\/strong><\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>En muchos casos, mejorar el flujo de materiales requiere una inversi\u00f3n mucho menor que ampliar la capacidad de producci\u00f3n o adquirir m\u00e1quinas adicionales.<\/p>\n\n\n\n<p>Para los fabricantes de pl\u00e1sticos que buscan aumentar la eficiencia, el pr\u00f3ximo aumento de la productividad puede no venir de a\u00f1adir m\u00e1s equipos. Puede venir de abordar un eslab\u00f3n perdido en la eficiencia de la producci\u00f3n: c\u00f3mo se mueven los materiales por la f\u00e1brica. <\/p>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-columns is-style-xl-gutter is-layout-flex wp-container-core-columns-is-layout-2d85a6ef wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--80);margin-bottom:var(--wp--preset--spacing--80)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h4 class=\"wp-block-heading has-palette-brand-1-color has-text-color has-link-color wp-elements-cbdbe5d56e8ab0a7024a319eda487fab\" id=\"h-the-next-step\" style=\"text-transform:none\">El siguiente paso  <\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><a href=\"https:\/\/kongskilde-industries.com\/industrial\/contact\/\" data-type=\"page\" data-id=\"4877\">Contacte con nosotros hoy mismo<\/a> para descubrir c\u00f3mo Kongskilde puede ayudarle a construir un proceso de producci\u00f3n m\u00e1s seguro, eficiente y sostenible.<\/p>\n<\/div>\n<\/div>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<hr class=\"wp-block-separator has-text-color has-palette-bg-alt-color has-alpha-channel-opacity has-palette-bg-alt-background-color has-background\"\/>\n\n<p class=\"has-small-font-size\"><strong>Fuentes<\/strong><\/p>\n\n<p style=\"font-size:10px\">1. <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/pii\/S2405896321009642?utm_source\">https:\/\/www.sciencedirect.com\/science\/article\/pii\/S2405896321009642?utm_source<\/a><\/p>\n\n<p style=\"font-size:10px\">2. Vea el caso aqu\u00ed: https: <a href=\"https:\/\/kongskilde-industries.com\/industrial\/cases\/removal-of-plastic-wrap-from-liquor-bottles-france\/\" target=\"_blank\" rel=\"noreferrer noopener\">\/\/kongskilde-industries.com\/industrial\/cases\/removal-of-plastic-wrap-from-liquor-bottles-france\/<\/a><\/p>\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group alignfull has-palette-light-background-color has-background\" id=\"products\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33%\">\n<h2 class=\"wp-block-heading no-margin-bottom\" id=\"h-related-articles\">Art\u00edculos relacionados<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66%\">\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><a class=\"wp-block-card__link card_btn-type\" href=\"https:\/\/kongskilde-industries.com\/industrial\/cases\/removal-of-plastic-wrap-from-liquor-bottles-france\/\"><div class=\"wp-block-card  aligncenter\"><div class=\"card--image cover-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"600\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Martell-France-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Martell-France-1.jpg 1200w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Martell-France-1-600x300.jpg 600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><div class=\"card--content\"><h3 class=\"card_heading\">Eliminaci\u00f3n del envoltorio de pl\u00e1stico para la producci\u00f3n de botellas<\/h3><div class=\"card_desc\">Eliminaci\u00f3n del envoltorio de pl\u00e1stico para una producci\u00f3n de botellas m\u00e1s limpia y eficaz<\/div><div class=\"card_btn\"><span>M\u00e1s informaci\u00f3n<\/span><\/div><\/div><\/div><\/a><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><a class=\"wp-block-card__link card_btn-type\" href=\"https:\/\/kongskilde-industries.com\/industrial\/cases\/airwash-plastics-recycling-plant-poland\/\"><div class=\"wp-block-card  aligncenter\"><div class=\"card--image cover-1\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1800\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/JM-Trade-featured-image.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/JM-Trade-featured-image.jpg 2000w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/JM-Trade-featured-image-600x540.jpg 600w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/div><div class=\"card--content\"><h3 class=\"card_heading\">Separaci\u00f3n y desempolvado para el reciclado de pl\u00e1sticos<\/h3><div class=\"card_desc\">Separaci\u00f3n del pl\u00e1stico triturado para aumentar el rendimiento y la calidad del material<\/div><div class=\"card_btn\"><span>M\u00e1s informaci\u00f3n<\/span><\/div><\/div><\/div><\/a><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><a class=\"wp-block-card__link card_btn-type\" href=\"https:\/\/kongskilde-industries.com\/industrial\/cases\/film-waste-extraction-and-shredding-for-flexible-packaging-production-poland\/\"><div class=\"wp-block-card  aligncenter\"><div class=\"card--image cover-1\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"857\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/1675319970427_WebOp.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/1675319970427_WebOp.jpg 900w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/1675319970427_WebOp-600x571.jpg 600w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><div class=\"card--content\"><h3 class=\"card_heading\">Extracci\u00f3n y trituraci\u00f3n de residuos de film para envasado<\/h3><div class=\"card_desc\">Extracci\u00f3n y trituraci\u00f3n de residuos de film para la producci\u00f3n de envases flexibles<\/div><div class=\"card_btn\"><span>M\u00e1s informaci\u00f3n<\/span><\/div><\/div><\/div><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-cover is-light\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-palette-bg-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-palette-attention-color has-text-color has-link-color wp-elements-34a765f63f7408eec60dc488bd46e7ba\" style=\"font-size:1.75em\"><strong>Estamos aqu\u00ed para ayudarle a encontrar la soluci\u00f3n adecuada para la manipulaci\u00f3n de materiales.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\">Inicie la conversaci\u00f3n hoy mismo.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/kongskilde-industries.com\/industrial\/contact\/\">Contacte con nosotros<\/a><\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Muchas ganancias de producci\u00f3n en la fabricaci\u00f3n de pl\u00e1sticos no proceden de a\u00f1adir equipos, sino de mejorar la forma en que los materiales se mueven a trav\u00e9s del proceso.<\/p>\n","protected":false},"author":5,"featured_media":82950,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[150],"tags":[766],"class_list":["post-82975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-industriales","tag-articulo"],"acf":{"footer_cta_override":"default","remove_footer_margin":false,"footer_cta":{"background_image":null,"product_image":null,"heading":"","subheading":"","link":null,"link_secondary":null}},"featured_image_src":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Various-plastic-pellets_lids_bags_trim.png","author_info":{"display_name":"breewunderlich","author_link":"https:\/\/kongskilde-industries.com\/es\/author\/breewunderlich\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El eslab\u00f3n perdido en la eficiencia de la producci\u00f3n de pl\u00e1sticos - Kongskilde Industries<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El eslab\u00f3n perdido en la eficiencia de la producci\u00f3n de pl\u00e1sticos\" \/>\n<meta property=\"og:description\" content=\"Muchas ganancias de producci\u00f3n en la fabricaci\u00f3n de pl\u00e1sticos no proceden de a\u00f1adir equipos, sino de mejorar la forma en que los materiales se mueven a trav\u00e9s del proceso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kongskilde-industries.com\/es\/the-missing-link-in-plastics-production-efficiency\/\" \/>\n<meta property=\"og:site_name\" content=\"Kongskilde Industries\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kongskildegrain\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T09:27:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T09:28:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Various-plastic-pellets_lids_bags_trim.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1774\" \/>\n\t<meta property=\"og:image:height\" content=\"887\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"breewunderlich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/the-missing-link-in-plastics-production-efficiency\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/the-missing-link-in-plastics-production-efficiency\\\/\"},\"author\":{\"name\":\"breewunderlich\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\"},\"headline\":\"El eslab\u00f3n perdido en la eficiencia de la producci\u00f3n de pl\u00e1sticos\",\"datePublished\":\"2026-05-11T09:27:43+00:00\",\"dateModified\":\"2026-05-11T09:28:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/the-missing-link-in-plastics-production-efficiency\\\/\"},\"wordCount\":1633,\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/the-missing-link-in-plastics-production-efficiency\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Various-plastic-pellets_lids_bags_trim.png\",\"keywords\":[\"Art\u00edculo\"],\"articleSection\":[\"Noticias Industriales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/the-missing-link-in-plastics-production-efficiency\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/the-missing-link-in-plastics-production-efficiency\\\/\",\"name\":\"El eslab\u00f3n perdido en la eficiencia de la producci\u00f3n de pl\u00e1sticos - Kongskilde Industries\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/the-missing-link-in-plastics-production-efficiency\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/the-missing-link-in-plastics-production-efficiency\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Various-plastic-pellets_lids_bags_trim.png\",\"datePublished\":\"2026-05-11T09:27:43+00:00\",\"dateModified\":\"2026-05-11T09:28:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/the-missing-link-in-plastics-production-efficiency\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/the-missing-link-in-plastics-production-efficiency\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/the-missing-link-in-plastics-production-efficiency\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Various-plastic-pellets_lids_bags_trim.png\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Various-plastic-pellets_lids_bags_trim.png\",\"width\":1774,\"height\":887},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/the-missing-link-in-plastics-production-efficiency\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El eslab\u00f3n perdido en la eficiencia de la producci\u00f3n de pl\u00e1sticos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"name\":\"Kongskilde Industries\",\"description\":\"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"alternateName\":\"Kongskilde\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\",\"name\":\"Kongskilde Industries\",\"alternateName\":\"Kongskilde\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"width\":2550,\"height\":392,\"caption\":\"Kongskilde Industries\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kongskildegrain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kongskilde-industries-a-s\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@kongskildeindustries\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\",\"name\":\"breewunderlich\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El eslab\u00f3n perdido en la eficiencia de la producci\u00f3n de pl\u00e1sticos - Kongskilde Industries","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"El eslab\u00f3n perdido en la eficiencia de la producci\u00f3n de pl\u00e1sticos","og_description":"Muchas ganancias de producci\u00f3n en la fabricaci\u00f3n de pl\u00e1sticos no proceden de a\u00f1adir equipos, sino de mejorar la forma en que los materiales se mueven a trav\u00e9s del proceso.","og_url":"https:\/\/kongskilde-industries.com\/es\/the-missing-link-in-plastics-production-efficiency\/","og_site_name":"Kongskilde Industries","article_publisher":"https:\/\/www.facebook.com\/kongskildegrain","article_published_time":"2026-05-11T09:27:43+00:00","article_modified_time":"2026-05-11T09:28:19+00:00","og_image":[{"url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Various-plastic-pellets_lids_bags_trim.png","width":1774,"height":887,"type":"image\/png"}],"author":"breewunderlich","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/kongskilde-industries.com\/es\/the-missing-link-in-plastics-production-efficiency\/#article","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/the-missing-link-in-plastics-production-efficiency\/"},"author":{"name":"breewunderlich","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb"},"headline":"El eslab\u00f3n perdido en la eficiencia de la producci\u00f3n de pl\u00e1sticos","datePublished":"2026-05-11T09:27:43+00:00","dateModified":"2026-05-11T09:28:19+00:00","mainEntityOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/the-missing-link-in-plastics-production-efficiency\/"},"wordCount":1633,"publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/the-missing-link-in-plastics-production-efficiency\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Various-plastic-pellets_lids_bags_trim.png","keywords":["Art\u00edculo"],"articleSection":["Noticias Industriales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kongskilde-industries.com\/es\/the-missing-link-in-plastics-production-efficiency\/","url":"https:\/\/kongskilde-industries.com\/es\/the-missing-link-in-plastics-production-efficiency\/","name":"El eslab\u00f3n perdido en la eficiencia de la producci\u00f3n de pl\u00e1sticos - Kongskilde Industries","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/the-missing-link-in-plastics-production-efficiency\/#primaryimage"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/the-missing-link-in-plastics-production-efficiency\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Various-plastic-pellets_lids_bags_trim.png","datePublished":"2026-05-11T09:27:43+00:00","dateModified":"2026-05-11T09:28:19+00:00","breadcrumb":{"@id":"https:\/\/kongskilde-industries.com\/es\/the-missing-link-in-plastics-production-efficiency\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kongskilde-industries.com\/es\/the-missing-link-in-plastics-production-efficiency\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/the-missing-link-in-plastics-production-efficiency\/#primaryimage","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Various-plastic-pellets_lids_bags_trim.png","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Various-plastic-pellets_lids_bags_trim.png","width":1774,"height":887},{"@type":"BreadcrumbList","@id":"https:\/\/kongskilde-industries.com\/es\/the-missing-link-in-plastics-production-efficiency\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kongskilde-industries.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"El eslab\u00f3n perdido en la eficiencia de la producci\u00f3n de pl\u00e1sticos"}]},{"@type":"WebSite","@id":"https:\/\/kongskilde-industries.com\/es\/#website","url":"https:\/\/kongskilde-industries.com\/es\/","name":"Kongskilde Industries","description":"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.","publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"alternateName":"Kongskilde","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kongskilde-industries.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kongskilde-industries.com\/es\/#organization","name":"Kongskilde Industries","alternateName":"Kongskilde","url":"https:\/\/kongskilde-industries.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","width":2550,"height":392,"caption":"Kongskilde Industries"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kongskildegrain","https:\/\/www.linkedin.com\/company\/kongskilde-industries-a-s\/","https:\/\/www.youtube.com\/@kongskildeindustries"]},{"@type":"Person","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb","name":"breewunderlich"}]}},"_links":{"self":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/82975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/comments?post=82975"}],"version-history":[{"count":1,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/82975\/revisions"}],"predecessor-version":[{"id":82976,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/82975\/revisions\/82976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media\/82950"}],"wp:attachment":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media?parent=82975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/categories?post=82975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/tags?post=82975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":82179,"date":"2026-01-13T10:44:35","date_gmt":"2026-01-13T10:44:35","guid":{"rendered":"https:\/\/kongskilde-industries.com\/pioneering-the-next-era-of-smart-material-handling\/"},"modified":"2026-04-07T10:19:43","modified_gmt":"2026-04-07T10:19:43","slug":"pioneering-the-next-era-of-smart-material-handling","status":"publish","type":"post","link":"https:\/\/kongskilde-industries.com\/es\/pioneering-the-next-era-of-smart-material-handling\/","title":{"rendered":"Pioneros en la pr\u00f3xima era de la manipulaci\u00f3n inteligente de materiales"},"content":{"rendered":"\n<p class=\"has-small-font-size\"><em>13 de enero de 2026<\/em><\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"454\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MultiAir_Warm_DSC8197_Web_Cropped.jpg\" alt=\"\" class=\"wp-image-82148\" srcset=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MultiAir_Warm_DSC8197_Web_Cropped.jpg 1200w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MultiAir_Warm_DSC8197_Web_Cropped-600x227.jpg 600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\" id=\"h-pioneering-the-next-era-of-smart-material-handling\"><strong>Pioneros en la pr\u00f3xima era de la manipulaci\u00f3n inteligente de materiales<\/strong><\/h2>\n\n<p><em>Aprovechando la experiencia demostrada en la manipulaci\u00f3n de materiales para satisfacer las necesidades cambiantes de la industria moderna<\/em><\/p>\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Kongskilde Industries est\u00e1 invirtiendo en la siguiente fase de crecimiento, reforzando la innovaci\u00f3n, la ejecuci\u00f3n y el valor para el cliente en todo el negocio global. Bas\u00e1ndose en d\u00e9cadas de experiencia en la manipulaci\u00f3n neum\u00e1tica de materiales, Kongskilde est\u00e1 mejorando sus capacidades para satisfacer las necesidades cambiantes de la industria moderna. Las soluciones de Kongskilde apoyan a los clientes dondequiera que grandes vol\u00famenes de materiales ligeros deban ser transportados, separados, limpiados, cortados o manipulados de cualquier otra forma con precisi\u00f3n y fiabilidad. Mejorando la eficiencia, reduciendo el riesgo operativo y ayudando a recuperar m\u00e1s valor de los materiales, estos sistemas refuerzan el rendimiento actual a la vez que apoyan lo que vendr\u00e1 en el futuro.   <\/p>\n\n<p>Bajo la direcci\u00f3n del CEO Oscar William Gunner, nombrado en junio de 2025, Kongskilde est\u00e1 afinando su enfoque en las \u00e1reas de mayor impacto y expandiendo su presencia en el mercado para llevar soluciones completas de manipulaci\u00f3n neum\u00e1tica de materiales a m\u00e1s industrias y aplicaciones. Bas\u00e1ndose en su fortaleza como proveedor de soluciones, Kongskilde est\u00e1 mejorando a\u00fan m\u00e1s la forma en que los sistemas son dise\u00f1ados, entregados y soportados para resolver los desaf\u00edos operativos reales y funcionar de forma fiable a lo largo del tiempo. <\/p>\n\n<div class=\"wp-block-columns has-palette-light-background-color has-background is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"398\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Oscar-William-Gunner-headshot_Web-Op.jpg\" alt=\"\" class=\"wp-image-82165\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\">\n<p><em>\u00abLos clientes conf\u00edan en Kongskilde porque nuestras soluciones neum\u00e1ticas ofrecen resultados. Esta transformaci\u00f3n consiste en reforzar c\u00f3mo innovamos, c\u00f3mo aportamos valor y c\u00f3mo apoyamos a los clientes en la construcci\u00f3n de operaciones del futuro m\u00e1s inteligentes y eficientes\u00bb. <\/em>.<em>\u00ab<\/em><\/p>\n\n\n\n<p><em>Oscar William Gunner, Director General de Kongskilde Industries A\/S<\/em><\/p>\n<\/div>\n<\/div>\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Una de las principales prioridades es facilitar a los responsables de la toma de decisiones la identificaci\u00f3n y selecci\u00f3n de la soluci\u00f3n de Kongskilde adecuada. A medida que las empresas realizan cada vez m\u00e1s sus propias investigaciones, se espera una informaci\u00f3n clara y una orientaci\u00f3n pr\u00e1ctica en las primeras fases del proceso. Para apoyar decisiones m\u00e1s r\u00e1pidas y m\u00e1s informadas, Kongskilde est\u00e1 reforzando su presencia digital mediante el desarrollo de la p\u00e1gina web en un recurso m\u00e1s fuerte con contenido pr\u00e1ctico y herramientas que ayudan a los equipos a evaluar soluciones y avanzar de manera eficiente.  <\/p>\n\n<p>Para apoyar a\u00fan m\u00e1s el crecimiento a largo plazo, Kongskilde est\u00e1 fortaleciendo su presencia global a trav\u00e9s de la alineaci\u00f3n entre regiones, mejorando los procesos comerciales y avanzando en la gesti\u00f3n y desarrollo de productos. Juntos, estos pasos ayudan a los clientes a tomar decisiones m\u00e1s r\u00e1pidas, implementarlas de forma fiable y recibir un fuerte apoyo de principio a fin, reforzando el papel de Kongskilde como l\u00edder mundial en la manipulaci\u00f3n neum\u00e1tica de materiales. <\/p>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\" id=\"h-about-kongskilde-industries\"><strong>Acerca de Kongskilde Industries<\/strong><\/h3>\n\n<p><em>Fundada en 1949 y con sede central en Dinamarca, Kongskilde Industries A\/S desarrolla y suministra soluciones de manipulaci\u00f3n neum\u00e1tica de materiales para las industrias del pl\u00e1stico, papel, reciclaje y agricultura. Nuestros sistemas ayudan a mejorar la eficiencia de la producci\u00f3n, apoyan el reciclaje y crean mejores entornos de trabajo. Con una presencia global y d\u00e9cadas de experiencia, Kongskilde Industries ofrece soluciones modulares y f\u00e1ciles de integrar respaldadas por una amplia experiencia.  <\/em><\/p>\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Kongskilde refuerza su estrategia global para ofrecer soluciones m\u00e1s inteligentes de manipulaci\u00f3n neum\u00e1tica de materiales, mejorando la eficiencia, la fiabilidad y la recuperaci\u00f3n de valor.<\/p>\n","protected":false},"author":5,"featured_media":82161,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[150,385],"tags":[758],"class_list":["post-82179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-industriales","category-noticias-cereales","tag-noticias"],"acf":{"footer_cta_override":"default","remove_footer_margin":false,"footer_cta":{"background_image":null,"product_image":null,"heading":"","subheading":"","link":null,"link_secondary":null}},"featured_image_src":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MultiAir_Warm_Featured-Image.jpg","author_info":{"display_name":"breewunderlich","author_link":"https:\/\/kongskilde-industries.com\/es\/author\/breewunderlich\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pioneros en la pr\u00f3xima era de la manipulaci\u00f3n inteligente de materiales - Kongskilde Industries<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pioneros en la pr\u00f3xima era de la manipulaci\u00f3n inteligente de materiales\" \/>\n<meta property=\"og:description\" content=\"Kongskilde refuerza su estrategia global para ofrecer soluciones m\u00e1s inteligentes de manipulaci\u00f3n neum\u00e1tica de materiales, mejorando la eficiencia, la fiabilidad y la recuperaci\u00f3n de valor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kongskilde-industries.com\/es\/pioneering-the-next-era-of-smart-material-handling\/\" \/>\n<meta property=\"og:site_name\" content=\"Kongskilde Industries\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kongskildegrain\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-13T10:44:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T10:19:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MultiAir_Warm_Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"breewunderlich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/pioneering-the-next-era-of-smart-material-handling\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/pioneering-the-next-era-of-smart-material-handling\\\/\"},\"author\":{\"name\":\"breewunderlich\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\"},\"headline\":\"Pioneros en la pr\u00f3xima era de la manipulaci\u00f3n inteligente de materiales\",\"datePublished\":\"2026-01-13T10:44:35+00:00\",\"dateModified\":\"2026-04-07T10:19:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/pioneering-the-next-era-of-smart-material-handling\\\/\"},\"wordCount\":595,\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/pioneering-the-next-era-of-smart-material-handling\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/MultiAir_Warm_Featured-Image.jpg\",\"keywords\":[\"Noticias\"],\"articleSection\":[\"Noticias Industriales\",\"Noticias sobre el grano\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/pioneering-the-next-era-of-smart-material-handling\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/pioneering-the-next-era-of-smart-material-handling\\\/\",\"name\":\"Pioneros en la pr\u00f3xima era de la manipulaci\u00f3n inteligente de materiales - Kongskilde Industries\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/pioneering-the-next-era-of-smart-material-handling\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/pioneering-the-next-era-of-smart-material-handling\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/MultiAir_Warm_Featured-Image.jpg\",\"datePublished\":\"2026-01-13T10:44:35+00:00\",\"dateModified\":\"2026-04-07T10:19:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/pioneering-the-next-era-of-smart-material-handling\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/pioneering-the-next-era-of-smart-material-handling\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/pioneering-the-next-era-of-smart-material-handling\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/MultiAir_Warm_Featured-Image.jpg\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/MultiAir_Warm_Featured-Image.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/pioneering-the-next-era-of-smart-material-handling\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pioneros en la pr\u00f3xima era de la manipulaci\u00f3n inteligente de materiales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"name\":\"Kongskilde Industries\",\"description\":\"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"alternateName\":\"Kongskilde\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\",\"name\":\"Kongskilde Industries\",\"alternateName\":\"Kongskilde\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"width\":2550,\"height\":392,\"caption\":\"Kongskilde Industries\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kongskildegrain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kongskilde-industries-a-s\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@kongskildeindustries\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\",\"name\":\"breewunderlich\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pioneros en la pr\u00f3xima era de la manipulaci\u00f3n inteligente de materiales - Kongskilde Industries","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Pioneros en la pr\u00f3xima era de la manipulaci\u00f3n inteligente de materiales","og_description":"Kongskilde refuerza su estrategia global para ofrecer soluciones m\u00e1s inteligentes de manipulaci\u00f3n neum\u00e1tica de materiales, mejorando la eficiencia, la fiabilidad y la recuperaci\u00f3n de valor.","og_url":"https:\/\/kongskilde-industries.com\/es\/pioneering-the-next-era-of-smart-material-handling\/","og_site_name":"Kongskilde Industries","article_publisher":"https:\/\/www.facebook.com\/kongskildegrain","article_published_time":"2026-01-13T10:44:35+00:00","article_modified_time":"2026-04-07T10:19:43+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MultiAir_Warm_Featured-Image.jpg","type":"image\/jpeg"}],"author":"breewunderlich","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/kongskilde-industries.com\/es\/pioneering-the-next-era-of-smart-material-handling\/#article","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/pioneering-the-next-era-of-smart-material-handling\/"},"author":{"name":"breewunderlich","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb"},"headline":"Pioneros en la pr\u00f3xima era de la manipulaci\u00f3n inteligente de materiales","datePublished":"2026-01-13T10:44:35+00:00","dateModified":"2026-04-07T10:19:43+00:00","mainEntityOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/pioneering-the-next-era-of-smart-material-handling\/"},"wordCount":595,"publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/pioneering-the-next-era-of-smart-material-handling\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MultiAir_Warm_Featured-Image.jpg","keywords":["Noticias"],"articleSection":["Noticias Industriales","Noticias sobre el grano"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kongskilde-industries.com\/es\/pioneering-the-next-era-of-smart-material-handling\/","url":"https:\/\/kongskilde-industries.com\/es\/pioneering-the-next-era-of-smart-material-handling\/","name":"Pioneros en la pr\u00f3xima era de la manipulaci\u00f3n inteligente de materiales - Kongskilde Industries","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/pioneering-the-next-era-of-smart-material-handling\/#primaryimage"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/pioneering-the-next-era-of-smart-material-handling\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MultiAir_Warm_Featured-Image.jpg","datePublished":"2026-01-13T10:44:35+00:00","dateModified":"2026-04-07T10:19:43+00:00","breadcrumb":{"@id":"https:\/\/kongskilde-industries.com\/es\/pioneering-the-next-era-of-smart-material-handling\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kongskilde-industries.com\/es\/pioneering-the-next-era-of-smart-material-handling\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/pioneering-the-next-era-of-smart-material-handling\/#primaryimage","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MultiAir_Warm_Featured-Image.jpg","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MultiAir_Warm_Featured-Image.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/kongskilde-industries.com\/es\/pioneering-the-next-era-of-smart-material-handling\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kongskilde-industries.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Pioneros en la pr\u00f3xima era de la manipulaci\u00f3n inteligente de materiales"}]},{"@type":"WebSite","@id":"https:\/\/kongskilde-industries.com\/es\/#website","url":"https:\/\/kongskilde-industries.com\/es\/","name":"Kongskilde Industries","description":"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.","publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"alternateName":"Kongskilde","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kongskilde-industries.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kongskilde-industries.com\/es\/#organization","name":"Kongskilde Industries","alternateName":"Kongskilde","url":"https:\/\/kongskilde-industries.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","width":2550,"height":392,"caption":"Kongskilde Industries"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kongskildegrain","https:\/\/www.linkedin.com\/company\/kongskilde-industries-a-s\/","https:\/\/www.youtube.com\/@kongskildeindustries"]},{"@type":"Person","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb","name":"breewunderlich"}]}},"_links":{"self":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/82179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/comments?post=82179"}],"version-history":[{"count":1,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/82179\/revisions"}],"predecessor-version":[{"id":82429,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/82179\/revisions\/82429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media\/82161"}],"wp:attachment":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media?parent=82179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/categories?post=82179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/tags?post=82179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":82045,"date":"2025-10-08T07:00:00","date_gmt":"2025-10-08T07:00:00","guid":{"rendered":"https:\/\/kongskilde-industries.com\/new-product-waste-screw-compactor-for-cub\/"},"modified":"2026-04-07T10:20:30","modified_gmt":"2026-04-07T10:20:30","slug":"new-product-waste-screw-compactor-for-cub","status":"publish","type":"post","link":"https:\/\/kongskilde-industries.com\/es\/new-product-waste-screw-compactor-for-cub\/","title":{"rendered":"NUEVO PRODUCTO: Compactador de residuos de tornillo para CUB"},"content":{"rendered":"\n<p><em>8 de octubre de 2025<\/em><\/p>\n\n<div style=\"height:2px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-cover\" style=\"min-height:200px;aspect-ratio:unset;\"><img decoding=\"async\" class=\"wp-block-cover__image-background wp-image-85115 size-full\" alt=\"\" src=\"https:\/\/kongskilde-industries.com\/industrial\/wp-content\/uploads\/sites\/3\/CUB-with-Screw-Compactor_Blurred-Background_Web-Op.jpg\" style=\"object-position:45% 76%\" data-object-fit=\"cover\" data-object-position=\"45% 76%\"\/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-palette-brand-1-background-color has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size\"><\/p>\n<\/div><\/div>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\" id=\"h-introducing-the-new-waste-screw-compactor-for-the-cub-1600\">Presentamos el nuevo compactador de tornillo de residuos para el CUB-1600<\/h2>\n\n<p>Kongskilde Industries se enorgullece en anunciar el lanzamiento del nuevo <strong>Compactador de Tornillos de Residuos<\/strong> para la <a href=\"https:\/\/kongskilde-industries.com\/industrial\/product\/compact-unit-cub\/\" data-type=\"products\" data-id=\"79153\">Unidad Todo en Uno CUB<\/a>, reforzando a\u00fan m\u00e1s la reputaci\u00f3n del CUB como un sistema de recogida de residuos vers\u00e1til y flexible. Esta nueva incorporaci\u00f3n est\u00e1 pensada para los fabricantes que necesitan una soluci\u00f3n compacta y flexible que pueda hacer frente a las exigencias de las instalaciones de gran capacidad en los sectores de las etiquetas, la impresi\u00f3n, el film, la extrusi\u00f3n y el envasado. <\/p>\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-cover alignfull is-light\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-palette-light-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns is-style-xl-gutter is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading\" id=\"h-key-features\">Caracter\u00edsticas principales:<\/h2>\n\n\n\n<p><strong>Funcionamiento continuo:<\/strong> La compactadora alimenta los materiales cortados directamente en cubos de basura est\u00e1ndar, reduciendo la necesidad de cambiar las bolsas y permitiendo que la producci\u00f3n contin\u00fae con menos interrupciones.<\/p>\n\n\n\n<p><strong>Flexible y vers\u00e1til: <\/strong>la unidad procesa papel, pl\u00e1sticos, etiquetas, l\u00e1minas y cart\u00f3n fino con facilidad, y tambi\u00e9n est\u00e1 disponible en versi\u00f3n antiadherente para materiales adhesivos y en versi\u00f3n antiest\u00e1tica para residuos propensos a la electricidad est\u00e1tica.<\/p>\n\n\n\n<p><strong>Compacta, adaptable y potente: <\/strong>Ofrece una manipulaci\u00f3n de residuos consistente y fiable en un dise\u00f1o compacto que se integra a la perfecci\u00f3n con el CUB-1600. Puede montarse en tres posiciones diferentes y est\u00e1 disponible con un soporte opcional, lo que facilita su adaptaci\u00f3n a los dise\u00f1os de producci\u00f3n. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/kongskilde-industries.com\/industrial\/wp-content\/uploads\/sites\/3\/CUB-with-Screw-Compactor_transparent_Web-Op.png\" alt=\"\" class=\"wp-image-85098\"\/><\/figure>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\" id=\"h-flexible-and-easy-to-integrate\">Flexible y f\u00e1cil de integrar<\/h2>\n\n<p>Como extensi\u00f3n del dise\u00f1o todo en uno del CUB, el compactador de tornillo sinf\u00edn de residuos mejora la eficiencia automatizando la manipulaci\u00f3n de los residuos y reduciendo las necesidades de mano de obra. Los operarios pueden centrarse en la producci\u00f3n en lugar de en la gesti\u00f3n de residuos, lo que se traduce en un mayor tiempo de actividad, menores costes y una mayor seguridad en el lugar de trabajo. <\/p>\n\n<p>El sistema compacta y acondiciona el material de desecho para facilitar su manipulaci\u00f3n, almacenamiento y traslado a las operaciones de reciclaje.<\/p>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-cover alignfull is-light\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-palette-light-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<h2 class=\"wp-block-heading no-padding-bottom\" id=\"h-customer-benefits\">Beneficios para el cliente<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Mayor productividad<\/strong> &#8211; El funcionamiento continuo y la capacidad ilimitada garantizan que la manipulaci\u00f3n de residuos siga el ritmo de la producci\u00f3n de gran volumen, eliminando paradas innecesarias.<\/li>\n\n\n\n<li><strong>Reducci\u00f3n del trabajo manual<\/strong> &#8211; Los residuos se compactan directamente en los cubos, lo que minimiza la manipulaci\u00f3n manual y permite a los operarios centrarse en la producci\u00f3n.<\/li>\n\n\n\n<li><strong>Mayor seguridad en el lugar de trabajo<\/strong> &#8211; Menos polvo y menos tareas de manipulaci\u00f3n manual crean unas condiciones de trabajo m\u00e1s seguras, respaldadas por unos controles sencillos y f\u00e1ciles de usar.<\/li>\n\n\n\n<li><strong>Menos recogidas<\/strong> de residuos &#8211; Al compactar los residuos para maximizar la capacidad de los contenedores y del transporte, el sistema reduce el n\u00famero de recogidas de residuos necesarias y apoya los objetivos de reciclaje.<\/li>\n\n\n\n<li><strong>Aprovechamiento del espacio<\/strong> &#8211; El dise\u00f1o compacto ayuda a mantener una disposici\u00f3n de la producci\u00f3n limpia y organizada.<\/li>\n\n\n\n<li><strong>F\u00e1cil integraci\u00f3n<\/strong> &#8211; Dise\u00f1ada para funcionar a la perfecci\u00f3n con la CUB-1600, una unidad m\u00f3vil todo en uno que puede colocarse f\u00e1cilmente entre las m\u00e1quinas seg\u00fan sea necesario.<\/li>\n<\/ul>\n<\/div><\/div>\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading\" id=\"h-shaping-the-future-of-waste-management\">Modelar el futuro de la gesti\u00f3n de residuos<\/h2>\n\n\n\n<p>El compactador de tornillo de residuos ha sido desarrollado para satisfacer las realidades de las plantas de producci\u00f3n actuales, donde el funcionamiento continuo, la flexibilidad y las pr\u00e1cticas sostenibles son esenciales. Dise\u00f1ado para integrarse f\u00e1cilmente con la unidad Todo en Uno CUB-1600, proporciona a los fabricantes una soluci\u00f3n eficaz de gesti\u00f3n de residuos que se adapta f\u00e1cilmente a las demandas cambiantes. <\/p>\n\n\n\n<p class=\"is-style-cta-link\"><a data-type=\"products\" data-id=\"79153\" href=\"https:\/\/kongskilde-industries.com\/industrial\/product\/compact-unit-cub\/\">M\u00e1s informaci\u00f3n sobre el CUB<\/a><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--3\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/kongskilde-industries.com\/industrial\/case-studies\/\">Casos de \u00e9xito<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/kongskilde-industries.com\/industrial\/contact\/\">Contacte con nosotros<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/kongskilde-industries.com\/industrial\/wp-content\/uploads\/sites\/3\/CUB-with-Screw-Compactor_Blurred-Background_Web-Op.jpg\" alt=\"\" class=\"wp-image-85115\"\/><\/figure>\n<\/div>\n<\/div>\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kongskilde Industries se enorgullece en anunciar el lanzamiento del nuevo Compactador de Tornillos de Residuos para la Unidad Todo en Uno CUB, reforzando a\u00fan m\u00e1s la reputaci\u00f3n del CUB como un sistema de recogida de residuos vers\u00e1til y flexible.  <\/p>\n","protected":false},"author":5,"featured_media":82028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[150],"tags":[758],"class_list":["post-82045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-industriales","tag-noticias"],"acf":{"footer_cta_override":"default","remove_footer_margin":false,"footer_cta":{"background_image":null,"product_image":null,"heading":"","subheading":"","link":null,"link_secondary":null}},"featured_image_src":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-with-Screw-Compactor_Blurred-Background_Hero-1200px.jpg","author_info":{"display_name":"breewunderlich","author_link":"https:\/\/kongskilde-industries.com\/es\/author\/breewunderlich\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NUEVO PRODUCTO: Compactador de residuos de tornillo para CUB - Kongskilde Industries<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUEVO PRODUCTO: Compactador de residuos de tornillo para CUB\" \/>\n<meta property=\"og:description\" content=\"Kongskilde Industries se enorgullece en anunciar el lanzamiento del nuevo Compactador de Tornillos de Residuos para la Unidad Todo en Uno CUB, reforzando a\u00fan m\u00e1s la reputaci\u00f3n del CUB como un sistema de recogida de residuos vers\u00e1til y flexible.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kongskilde-industries.com\/es\/new-product-waste-screw-compactor-for-cub\/\" \/>\n<meta property=\"og:site_name\" content=\"Kongskilde Industries\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kongskildegrain\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-08T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T10:20:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-with-Screw-Compactor_Blurred-Background_Hero-1200px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"797\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"breewunderlich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/new-product-waste-screw-compactor-for-cub\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/new-product-waste-screw-compactor-for-cub\\\/\"},\"author\":{\"name\":\"breewunderlich\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\"},\"headline\":\"NUEVO PRODUCTO: Compactador de residuos de tornillo para CUB\",\"datePublished\":\"2025-10-08T07:00:00+00:00\",\"dateModified\":\"2026-04-07T10:20:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/new-product-waste-screw-compactor-for-cub\\\/\"},\"wordCount\":634,\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/new-product-waste-screw-compactor-for-cub\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/CUB-with-Screw-Compactor_Blurred-Background_Hero-1200px.jpg\",\"keywords\":[\"Noticias\"],\"articleSection\":[\"Noticias Industriales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/new-product-waste-screw-compactor-for-cub\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/new-product-waste-screw-compactor-for-cub\\\/\",\"name\":\"NUEVO PRODUCTO: Compactador de residuos de tornillo para CUB - Kongskilde Industries\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/new-product-waste-screw-compactor-for-cub\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/new-product-waste-screw-compactor-for-cub\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/CUB-with-Screw-Compactor_Blurred-Background_Hero-1200px.jpg\",\"datePublished\":\"2025-10-08T07:00:00+00:00\",\"dateModified\":\"2026-04-07T10:20:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/new-product-waste-screw-compactor-for-cub\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/new-product-waste-screw-compactor-for-cub\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/new-product-waste-screw-compactor-for-cub\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/CUB-with-Screw-Compactor_Blurred-Background_Hero-1200px.jpg\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/CUB-with-Screw-Compactor_Blurred-Background_Hero-1200px.jpg\",\"width\":1200,\"height\":797},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/new-product-waste-screw-compactor-for-cub\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUEVO PRODUCTO: Compactador de residuos de tornillo para CUB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"name\":\"Kongskilde Industries\",\"description\":\"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"alternateName\":\"Kongskilde\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\",\"name\":\"Kongskilde Industries\",\"alternateName\":\"Kongskilde\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"width\":2550,\"height\":392,\"caption\":\"Kongskilde Industries\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kongskildegrain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kongskilde-industries-a-s\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@kongskildeindustries\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\",\"name\":\"breewunderlich\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NUEVO PRODUCTO: Compactador de residuos de tornillo para CUB - Kongskilde Industries","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"NUEVO PRODUCTO: Compactador de residuos de tornillo para CUB","og_description":"Kongskilde Industries se enorgullece en anunciar el lanzamiento del nuevo Compactador de Tornillos de Residuos para la Unidad Todo en Uno CUB, reforzando a\u00fan m\u00e1s la reputaci\u00f3n del CUB como un sistema de recogida de residuos vers\u00e1til y flexible.","og_url":"https:\/\/kongskilde-industries.com\/es\/new-product-waste-screw-compactor-for-cub\/","og_site_name":"Kongskilde Industries","article_publisher":"https:\/\/www.facebook.com\/kongskildegrain","article_published_time":"2025-10-08T07:00:00+00:00","article_modified_time":"2026-04-07T10:20:30+00:00","og_image":[{"width":1200,"height":797,"url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-with-Screw-Compactor_Blurred-Background_Hero-1200px.jpg","type":"image\/jpeg"}],"author":"breewunderlich","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/kongskilde-industries.com\/es\/new-product-waste-screw-compactor-for-cub\/#article","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/new-product-waste-screw-compactor-for-cub\/"},"author":{"name":"breewunderlich","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb"},"headline":"NUEVO PRODUCTO: Compactador de residuos de tornillo para CUB","datePublished":"2025-10-08T07:00:00+00:00","dateModified":"2026-04-07T10:20:30+00:00","mainEntityOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/new-product-waste-screw-compactor-for-cub\/"},"wordCount":634,"publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/new-product-waste-screw-compactor-for-cub\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-with-Screw-Compactor_Blurred-Background_Hero-1200px.jpg","keywords":["Noticias"],"articleSection":["Noticias Industriales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kongskilde-industries.com\/es\/new-product-waste-screw-compactor-for-cub\/","url":"https:\/\/kongskilde-industries.com\/es\/new-product-waste-screw-compactor-for-cub\/","name":"NUEVO PRODUCTO: Compactador de residuos de tornillo para CUB - Kongskilde Industries","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/new-product-waste-screw-compactor-for-cub\/#primaryimage"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/new-product-waste-screw-compactor-for-cub\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-with-Screw-Compactor_Blurred-Background_Hero-1200px.jpg","datePublished":"2025-10-08T07:00:00+00:00","dateModified":"2026-04-07T10:20:30+00:00","breadcrumb":{"@id":"https:\/\/kongskilde-industries.com\/es\/new-product-waste-screw-compactor-for-cub\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kongskilde-industries.com\/es\/new-product-waste-screw-compactor-for-cub\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/new-product-waste-screw-compactor-for-cub\/#primaryimage","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-with-Screw-Compactor_Blurred-Background_Hero-1200px.jpg","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-with-Screw-Compactor_Blurred-Background_Hero-1200px.jpg","width":1200,"height":797},{"@type":"BreadcrumbList","@id":"https:\/\/kongskilde-industries.com\/es\/new-product-waste-screw-compactor-for-cub\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kongskilde-industries.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"NUEVO PRODUCTO: Compactador de residuos de tornillo para CUB"}]},{"@type":"WebSite","@id":"https:\/\/kongskilde-industries.com\/es\/#website","url":"https:\/\/kongskilde-industries.com\/es\/","name":"Kongskilde Industries","description":"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.","publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"alternateName":"Kongskilde","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kongskilde-industries.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kongskilde-industries.com\/es\/#organization","name":"Kongskilde Industries","alternateName":"Kongskilde","url":"https:\/\/kongskilde-industries.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","width":2550,"height":392,"caption":"Kongskilde Industries"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kongskildegrain","https:\/\/www.linkedin.com\/company\/kongskilde-industries-a-s\/","https:\/\/www.youtube.com\/@kongskildeindustries"]},{"@type":"Person","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb","name":"breewunderlich"}]}},"_links":{"self":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/82045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/comments?post=82045"}],"version-history":[{"count":0,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/82045\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media\/82028"}],"wp:attachment":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media?parent=82045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/categories?post=82045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/tags?post=82045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":81964,"date":"2025-06-02T13:04:46","date_gmt":"2025-06-02T13:04:46","guid":{"rendered":"https:\/\/kongskilde-industries.com\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/"},"modified":"2026-04-07T10:31:58","modified_gmt":"2026-04-07T10:31:58","slug":"kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo","status":"publish","type":"post","link":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/","title":{"rendered":"Kongskilde Industries da la bienvenida a Oscar William Gunner como nuevo Director General"},"content":{"rendered":"\n<p><em>2 de junio de 2025<\/em><\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1504\" height=\"369\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Oscar-and-Team-Banner_1.jpg\" alt=\"\" class=\"wp-image-81935\" srcset=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Oscar-and-Team-Banner_1.jpg 1504w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Oscar-and-Team-Banner_1-600x147.jpg 600w\" sizes=\"auto, (max-width: 1504px) 100vw, 1504px\" \/><figcaption class=\"wp-element-caption\"><em>Mimi Sofie Stabell, Oscar William Gunner, Frank Jacobsen, Anja Juhler Nielsen, Michael M\u00f8ller<\/em><\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\" id=\"h-kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\"><strong>Kongskilde Industries da la bienvenida a Oscar William Gunner como nuevo Director General<\/strong><\/h2>\n\n<p>A partir del 1 de junio de 2025, Oscar William Gunner se uni\u00f3 a Kongskilde Industries como nuestro nuevo Director General.<\/p>\n\n<p>Oscar aporta una amplia experiencia comercial y operativa, con un s\u00f3lido historial en la direcci\u00f3n de empresas manufactureras a trav\u00e9s del desarrollo estrat\u00e9gico, la transformaci\u00f3n y el crecimiento rentable. Durante los \u00faltimos cuatro a\u00f1os, ha sido consejero delegado de HBN-Teknik A\/S, un proveedor de automoci\u00f3n de nivel 1 y 2, donde dirigi\u00f3 la transformaci\u00f3n estrat\u00e9gica de la empresa. Anteriormente, ocup\u00f3 varios puestos de alta direcci\u00f3n en G&amp;O Maritime Group, un proveedor n\u00f3rdico l\u00edder de la industria mar\u00edtima, entre ellos el de Director Comercial y Director de Operaciones. Oscar es licenciado en Ingenier\u00eda Industrial y tiene un m\u00e1ster en Econom\u00eda y Administraci\u00f3n de Empresas por la Universidad del Sur de Dinamarca.   <\/p>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\">\n<p><strong><em>Oscar William Gunner dice:<br\/><\/em><\/strong><em>\u00abEstoy muy emocionado de unirme a Kongskilde Industries. Es una marca establecida desde hace mucho tiempo, con una orgullosa herencia, grandes personas y un potencial significativo. Estoy deseando trabajar con el consejo y con todo el equipo de Kongskilde Industries para liberar a\u00fan m\u00e1s este potencial y ofrecer valor a nuestros clientes y accionistas\u00bb.<\/em><\/p>\n\n\n\n<p>La perspectiva global de Oscar y su estilo de liderazgo colaborativo se alinean bien con los valores y ambiciones de Kongskilde Industries. Confiamos en que inspirar\u00e1 a nuestros equipos y reforzar\u00e1 a\u00fan m\u00e1s nuestra posici\u00f3n como empresa innovadora, centrada en el cliente y con un alcance global. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"860\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/IMG_8716_2.jpg\" alt=\"\" class=\"wp-image-81943\" srcset=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/IMG_8716_2.jpg 1000w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/IMG_8716_2-600x516.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/div>\n<\/div>\n\n<p><strong>Gert Andersen, presidente de Kongskilde Industries, afirma:<br\/><\/strong><em>\u00abEstoy encantado de que Oscar se una a Kongskilde Industries en este momento tan importante en el desarrollo de la compa\u00f1\u00eda. Su s\u00f3lida experiencia en el liderazgo comercial, operativo y de transformaci\u00f3n, junto con su enfoque empresarial, ser\u00e1 muy valiosa a medida que continuamos transformando Kongskilde Industries, manteniendo a los clientes y empleados en el centro de nuestra estrategia. <\/em><\/p>\n\n<p><em>Tambi\u00e9n me gustar\u00eda aprovechar esta oportunidad para agradecer a Jeppe Lund su liderazgo y sus contribuciones. Su orientaci\u00f3n durante la pandemia y los retos econ\u00f3micos posteriores fue inestimable, al igual que su papel en el fortalecimiento de nuestras operaciones.\u00bb <\/em><\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-about-kongskilde-industries\"><strong>Acerca de Kongskilde Industries<\/strong><\/h3>\n\n<p>Fundada en 1949 y con sede central en Dinamarca, Kongskilde Industries A\/S desarrolla y suministra soluciones de manipulaci\u00f3n neum\u00e1tica de materiales para las industrias del pl\u00e1stico, el papel y la agricultura, entre otras.<\/p>\n\n<p>Nuestros sistemas ayudan a mejorar la eficiencia de la producci\u00f3n, apoyan el reciclaje y crean mejores entornos de trabajo. Con una presencia global y d\u00e9cadas de experiencia, Kongskilde Industries ofrece soluciones modulares y f\u00e1ciles de integrar respaldadas por una amplia experiencia. <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p class=\"is-style-cta-link\"><a href=\"https:\/\/kongskilde-industries.com\/es\/landings-es\/celebrating-75-years-of-innovation\/\">M\u00e1s informaci\u00f3n sobre los 75 a\u00f1os de experiencia de Kongskilde Industries<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir del 1 de junio de 2025, Oscar William Gunner se uni\u00f3 a Kongskilde Industries como nuestro nuevo Director General.<\/p>\n","protected":false},"author":5,"featured_media":81949,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[150],"tags":[758],"class_list":["post-81964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-industriales","tag-noticias"],"acf":{"footer_cta_override":"default","remove_footer_margin":false,"footer_cta":{"background_image":null,"product_image":null,"heading":"","subheading":"","link":null,"link_secondary":null}},"featured_image_src":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/IMG_8716_2.jpg","author_info":{"display_name":"breewunderlich","author_link":"https:\/\/kongskilde-industries.com\/es\/author\/breewunderlich\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kongskilde Industries da la bienvenida a Oscar William Gunner como nuevo Director General - Kongskilde Industries<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kongskilde Industries da la bienvenida a Oscar William Gunner como nuevo Director General\" \/>\n<meta property=\"og:description\" content=\"A partir del 1 de junio de 2025, Oscar William Gunner se uni\u00f3 a Kongskilde Industries como nuestro nuevo Director General.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/\" \/>\n<meta property=\"og:site_name\" content=\"Kongskilde Industries\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kongskildegrain\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-02T13:04:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T10:31:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/IMG_8716_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"860\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"breewunderlich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\\\/\"},\"author\":{\"name\":\"breewunderlich\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\"},\"headline\":\"Kongskilde Industries da la bienvenida a Oscar William Gunner como nuevo Director General\",\"datePublished\":\"2025-06-02T13:04:46+00:00\",\"dateModified\":\"2026-04-07T10:31:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\\\/\"},\"wordCount\":509,\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/IMG_8716_2.jpg\",\"keywords\":[\"Noticias\"],\"articleSection\":[\"Noticias Industriales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\\\/\",\"name\":\"Kongskilde Industries da la bienvenida a Oscar William Gunner como nuevo Director General - Kongskilde Industries\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/IMG_8716_2.jpg\",\"datePublished\":\"2025-06-02T13:04:46+00:00\",\"dateModified\":\"2026-04-07T10:31:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/IMG_8716_2.jpg\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/IMG_8716_2.jpg\",\"width\":1000,\"height\":860},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kongskilde Industries da la bienvenida a Oscar William Gunner como nuevo Director General\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"name\":\"Kongskilde Industries\",\"description\":\"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"alternateName\":\"Kongskilde\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\",\"name\":\"Kongskilde Industries\",\"alternateName\":\"Kongskilde\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"width\":2550,\"height\":392,\"caption\":\"Kongskilde Industries\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kongskildegrain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kongskilde-industries-a-s\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@kongskildeindustries\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\",\"name\":\"breewunderlich\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kongskilde Industries da la bienvenida a Oscar William Gunner como nuevo Director General - Kongskilde Industries","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Kongskilde Industries da la bienvenida a Oscar William Gunner como nuevo Director General","og_description":"A partir del 1 de junio de 2025, Oscar William Gunner se uni\u00f3 a Kongskilde Industries como nuestro nuevo Director General.","og_url":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/","og_site_name":"Kongskilde Industries","article_publisher":"https:\/\/www.facebook.com\/kongskildegrain","article_published_time":"2025-06-02T13:04:46+00:00","article_modified_time":"2026-04-07T10:31:58+00:00","og_image":[{"width":1000,"height":860,"url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/IMG_8716_2.jpg","type":"image\/jpeg"}],"author":"breewunderlich","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/#article","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/"},"author":{"name":"breewunderlich","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb"},"headline":"Kongskilde Industries da la bienvenida a Oscar William Gunner como nuevo Director General","datePublished":"2025-06-02T13:04:46+00:00","dateModified":"2026-04-07T10:31:58+00:00","mainEntityOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/"},"wordCount":509,"publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/IMG_8716_2.jpg","keywords":["Noticias"],"articleSection":["Noticias Industriales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/","url":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/","name":"Kongskilde Industries da la bienvenida a Oscar William Gunner como nuevo Director General - Kongskilde Industries","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/#primaryimage"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/IMG_8716_2.jpg","datePublished":"2025-06-02T13:04:46+00:00","dateModified":"2026-04-07T10:31:58+00:00","breadcrumb":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/#primaryimage","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/IMG_8716_2.jpg","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/IMG_8716_2.jpg","width":1000,"height":860},{"@type":"BreadcrumbList","@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-welcomes-oscar-william-gunner-as-new-ceo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kongskilde-industries.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Kongskilde Industries da la bienvenida a Oscar William Gunner como nuevo Director General"}]},{"@type":"WebSite","@id":"https:\/\/kongskilde-industries.com\/es\/#website","url":"https:\/\/kongskilde-industries.com\/es\/","name":"Kongskilde Industries","description":"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.","publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"alternateName":"Kongskilde","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kongskilde-industries.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kongskilde-industries.com\/es\/#organization","name":"Kongskilde Industries","alternateName":"Kongskilde","url":"https:\/\/kongskilde-industries.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","width":2550,"height":392,"caption":"Kongskilde Industries"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kongskildegrain","https:\/\/www.linkedin.com\/company\/kongskilde-industries-a-s\/","https:\/\/www.youtube.com\/@kongskildeindustries"]},{"@type":"Person","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb","name":"breewunderlich"}]}},"_links":{"self":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/comments?post=81964"}],"version-history":[{"count":3,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81964\/revisions"}],"predecessor-version":[{"id":82860,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81964\/revisions\/82860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media\/81949"}],"wp:attachment":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media?parent=81964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/categories?post=81964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/tags?post=81964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":81703,"date":"2024-11-15T12:24:48","date_gmt":"2024-11-15T12:24:48","guid":{"rendered":"https:\/\/kongskilde-industries.com\/today-marks-kongskildes-75th-birthday\/"},"modified":"2026-04-07T10:32:57","modified_gmt":"2026-04-07T10:32:57","slug":"today-marks-kongskildes-75th-birthday","status":"publish","type":"post","link":"https:\/\/kongskilde-industries.com\/es\/today-marks-kongskildes-75th-birthday\/","title":{"rendered":"\u00a1Hoy se celebra el 75 cumplea\u00f1os de Kongskilde!"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1584\" height=\"396\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/LinkedIn-75-Years-Banner-1.jpg\" alt=\"\" class=\"wp-image-81687\" srcset=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/LinkedIn-75-Years-Banner-1.jpg 1584w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/LinkedIn-75-Years-Banner-1-600x150.jpg 600w\" sizes=\"auto, (max-width: 1584px) 100vw, 1584px\" \/><\/figure>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Hoy, 15 de noviembre de 2024, marca un hito importante en la historia de Kongskilde Industries, ya que celebramos 75 a\u00f1os de innovaci\u00f3n, excelencia y compromiso para ofrecer soluciones de vanguardia. Desde 1949, hemos aprovechado con orgullo el poder del aire para transformar industrias y potenciar negocios en todo el mundo. <\/p>\n\n\n\n<p>A lo largo de las d\u00e9cadas, hemos crecido desde nuestros inicios como pioneros en sopladores de granos agr\u00edcolas hasta convertirnos en un l\u00edder mundialmente reconocido en soluciones de transporte neum\u00e1tico, separaci\u00f3n, corte y desempolvado. Nuestro enfoque centrado en el cliente y nuestra dedicaci\u00f3n a la innovaci\u00f3n nos han permitido satisfacer las necesidades cambiantes de industrias como la del pl\u00e1stico, el papel, el envasado y la manipulaci\u00f3n de granos. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-a-legacy-of-excellence\">Un legado de excelencia<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Soluciones pioneras<\/strong>: Desde el primer Ventilador de Grano hasta las actuales tecnolog\u00edas de vanguardia impulsadas por aire, nuestra trayectoria se ha definido por la innovaci\u00f3n que impulsa la eficiencia y la sostenibilidad.<\/li>\n\n\n\n<li><strong>Impacto global<\/strong>: En todo el mundo se conf\u00eda en nuestras soluciones, que mejoran la fiabilidad de la producci\u00f3n, la sostenibilidad y el rendimiento en diversas industrias.<\/li>\n<\/ul>\n\n\n\n<p>Al celebrar este hito, hacemos extensivo nuestro m\u00e1s sincero agradecimiento a nuestros clientes, socios y al dedicado equipo que ha contribuido a nuestro viaje. Juntos, seguimos innovando, garantizando que la fiabilidad y la sostenibilidad sigan estando a la vanguardia de la producci\u00f3n moderna. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-insights-from-our-team\">Ideas de nuestro equipo<\/h3>\n\n\n\n<p>Conozca a las personas que est\u00e1n detr\u00e1s del \u00e9xito de Kongskildeen nuestra <a href=\"https:\/\/kongskilde-industries.com\/es\/landings-es\/celebrating-75-years-of-innovation\/\">p\u00e1gina del 75 aniversario.<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-palette-light-color has-alpha-channel-opacity has-palette-light-background-color has-background\"\/>\n\n\n\n<p><strong>\u00danase a nosotros en nuestro homenaje a los 75 a\u00f1os que llevamos ofreciendo soluciones fiables para la manipulaci\u00f3n de materiales.  <\/strong><\/p>\n\n\n\n<p class=\"is-style-cta-link\"><strong><a href=\"https:\/\/kongskilde-industries.com\/es\/landings-es\/celebrating-75-years-of-innovation\/\">Obtenga m\u00e1s informaci\u00f3n sobre nuestro legado y nuestras soluciones aqu\u00ed.<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-group is-style-rounded has-palette-light-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/kongskilde-industries.com\/industrial\/wp-content\/uploads\/sites\/3\/75-Year-Kongskilde-Logo-Finals-03.png\" alt=\"\" class=\"wp-image-79542\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>\u00a1Obtenga m\u00e1s informaci\u00f3n en nuestra p\u00e1gina <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-palette-interactive-color\">del 75\u00ba aniversario<\/mark>!<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--4\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/kongskilde-industries.com\/es\/landings-es\/celebrating-75-years-of-innovation\/\" target=\"_blank\" rel=\"noreferrer noopener\">M\u00e1s informaci\u00f3n<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-style-rounded has-palette-brand-1-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2084\" height=\"2084\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Social-Media-Font-Awesome_LinkedIn-White.png\" alt=\"\" class=\"wp-image-81694\" style=\"width:100px\" srcset=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Social-Media-Font-Awesome_LinkedIn-White.png 2084w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Social-Media-Font-Awesome_LinkedIn-White-600x600.png 600w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Social-Media-Font-Awesome_LinkedIn-White-300x300.png 300w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Social-Media-Font-Awesome_LinkedIn-White-60x60.png 60w\" sizes=\"auto, (max-width: 2084px) 100vw, 2084px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-palette-bg-color has-text-color has-link-color wp-elements-cb9fb7e9030a33000c09df6347837e36\" id=\"h-follow-kongskilde-on-social-media\"><strong>Siga a Kongskilde en <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-palette-interactive-color\">las redes sociales<\/mark><\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-center has-palette-bg-color has-text-color has-link-color wp-elements-7a7cd2a9b8c0fcca93a667527f9d5460\"><strong>\u00a1S\u00edganos en LinkedIn para estar al d\u00eda de las celebraciones de nuestro 75 aniversario!<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.linkedin.com\/company\/kongskilde-industries-a-s\/\" target=\"_blank\" rel=\"noreferrer noopener\">M\u00e1s informaci\u00f3n<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hoy, 15 de noviembre de 2024, marca un hito importante en la historia de Kongskilde Industries, ya que celebramos 75 a\u00f1os de innovaci\u00f3n, excelencia y compromiso para ofrecer soluciones de vanguardia. Desde 1949, hemos aprovechado con orgullo el poder del aire para transformar industrias y potenciar negocios en todo el [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":81281,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[150,385],"tags":[758],"class_list":["post-81703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-industriales","category-noticias-cereales","tag-noticias"],"acf":{"footer_cta_override":"default","remove_footer_margin":false,"footer_cta":{"background_image":null,"product_image":null,"heading":"","subheading":"","link":null,"link_secondary":null}},"featured_image_src":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Anniversary-Cover.jpg","author_info":{"display_name":"breewunderlich","author_link":"https:\/\/kongskilde-industries.com\/es\/author\/breewunderlich\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00a1Hoy se celebra el 75 cumplea\u00f1os de Kongskilde! - Kongskilde Industries<\/title>\n<meta name=\"description\" content=\"Desde 1949, Kongskilde ha suministrado soluciones de vanguardia impulsadas por aire. Celebre nuestro legado de fiabilidad, sostenibilidad e impacto global.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Hoy se celebra el 75 cumplea\u00f1os de Kongskilde!\" \/>\n<meta property=\"og:description\" content=\"Desde 1949, Kongskilde ha suministrado soluciones de vanguardia impulsadas por aire. Celebre nuestro legado de fiabilidad, sostenibilidad e impacto global.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kongskilde-industries.com\/es\/today-marks-kongskildes-75th-birthday\/\" \/>\n<meta property=\"og:site_name\" content=\"Kongskilde Industries\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kongskildegrain\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-15T12:24:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T10:32:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Anniversary-Cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"breewunderlich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/today-marks-kongskildes-75th-birthday\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/today-marks-kongskildes-75th-birthday\\\/\"},\"author\":{\"name\":\"breewunderlich\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\"},\"headline\":\"\u00a1Hoy se celebra el 75 cumplea\u00f1os de Kongskilde!\",\"datePublished\":\"2024-11-15T12:24:48+00:00\",\"dateModified\":\"2026-04-07T10:32:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/today-marks-kongskildes-75th-birthday\\\/\"},\"wordCount\":341,\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/today-marks-kongskildes-75th-birthday\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/75-Anniversary-Cover.jpg\",\"keywords\":[\"Noticias\"],\"articleSection\":[\"Noticias Industriales\",\"Noticias sobre el grano\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/today-marks-kongskildes-75th-birthday\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/today-marks-kongskildes-75th-birthday\\\/\",\"name\":\"\u00a1Hoy se celebra el 75 cumplea\u00f1os de Kongskilde! - Kongskilde Industries\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/today-marks-kongskildes-75th-birthday\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/today-marks-kongskildes-75th-birthday\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/75-Anniversary-Cover.jpg\",\"datePublished\":\"2024-11-15T12:24:48+00:00\",\"dateModified\":\"2026-04-07T10:32:57+00:00\",\"description\":\"Desde 1949, Kongskilde ha suministrado soluciones de vanguardia impulsadas por aire. Celebre nuestro legado de fiabilidad, sostenibilidad e impacto global.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/today-marks-kongskildes-75th-birthday\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/today-marks-kongskildes-75th-birthday\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/today-marks-kongskildes-75th-birthday\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/75-Anniversary-Cover.jpg\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/75-Anniversary-Cover.jpg\",\"width\":2000,\"height\":1500,\"caption\":\"75 Kongskilde 1949 - 2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/today-marks-kongskildes-75th-birthday\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Hoy se celebra el 75 cumplea\u00f1os de Kongskilde!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"name\":\"Kongskilde Industries\",\"description\":\"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"alternateName\":\"Kongskilde\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\",\"name\":\"Kongskilde Industries\",\"alternateName\":\"Kongskilde\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"width\":2550,\"height\":392,\"caption\":\"Kongskilde Industries\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kongskildegrain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kongskilde-industries-a-s\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@kongskildeindustries\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\",\"name\":\"breewunderlich\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00a1Hoy se celebra el 75 cumplea\u00f1os de Kongskilde! - Kongskilde Industries","description":"Desde 1949, Kongskilde ha suministrado soluciones de vanguardia impulsadas por aire. Celebre nuestro legado de fiabilidad, sostenibilidad e impacto global.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"\u00a1Hoy se celebra el 75 cumplea\u00f1os de Kongskilde!","og_description":"Desde 1949, Kongskilde ha suministrado soluciones de vanguardia impulsadas por aire. Celebre nuestro legado de fiabilidad, sostenibilidad e impacto global.","og_url":"https:\/\/kongskilde-industries.com\/es\/today-marks-kongskildes-75th-birthday\/","og_site_name":"Kongskilde Industries","article_publisher":"https:\/\/www.facebook.com\/kongskildegrain","article_published_time":"2024-11-15T12:24:48+00:00","article_modified_time":"2026-04-07T10:32:57+00:00","og_image":[{"width":2000,"height":1500,"url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Anniversary-Cover.jpg","type":"image\/jpeg"}],"author":"breewunderlich","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/kongskilde-industries.com\/es\/today-marks-kongskildes-75th-birthday\/#article","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/today-marks-kongskildes-75th-birthday\/"},"author":{"name":"breewunderlich","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb"},"headline":"\u00a1Hoy se celebra el 75 cumplea\u00f1os de Kongskilde!","datePublished":"2024-11-15T12:24:48+00:00","dateModified":"2026-04-07T10:32:57+00:00","mainEntityOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/today-marks-kongskildes-75th-birthday\/"},"wordCount":341,"publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/today-marks-kongskildes-75th-birthday\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Anniversary-Cover.jpg","keywords":["Noticias"],"articleSection":["Noticias Industriales","Noticias sobre el grano"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kongskilde-industries.com\/es\/today-marks-kongskildes-75th-birthday\/","url":"https:\/\/kongskilde-industries.com\/es\/today-marks-kongskildes-75th-birthday\/","name":"\u00a1Hoy se celebra el 75 cumplea\u00f1os de Kongskilde! - Kongskilde Industries","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/today-marks-kongskildes-75th-birthday\/#primaryimage"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/today-marks-kongskildes-75th-birthday\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Anniversary-Cover.jpg","datePublished":"2024-11-15T12:24:48+00:00","dateModified":"2026-04-07T10:32:57+00:00","description":"Desde 1949, Kongskilde ha suministrado soluciones de vanguardia impulsadas por aire. Celebre nuestro legado de fiabilidad, sostenibilidad e impacto global.","breadcrumb":{"@id":"https:\/\/kongskilde-industries.com\/es\/today-marks-kongskildes-75th-birthday\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kongskilde-industries.com\/es\/today-marks-kongskildes-75th-birthday\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/today-marks-kongskildes-75th-birthday\/#primaryimage","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Anniversary-Cover.jpg","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Anniversary-Cover.jpg","width":2000,"height":1500,"caption":"75 Kongskilde 1949 - 2024"},{"@type":"BreadcrumbList","@id":"https:\/\/kongskilde-industries.com\/es\/today-marks-kongskildes-75th-birthday\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kongskilde-industries.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"\u00a1Hoy se celebra el 75 cumplea\u00f1os de Kongskilde!"}]},{"@type":"WebSite","@id":"https:\/\/kongskilde-industries.com\/es\/#website","url":"https:\/\/kongskilde-industries.com\/es\/","name":"Kongskilde Industries","description":"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.","publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"alternateName":"Kongskilde","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kongskilde-industries.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kongskilde-industries.com\/es\/#organization","name":"Kongskilde Industries","alternateName":"Kongskilde","url":"https:\/\/kongskilde-industries.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","width":2550,"height":392,"caption":"Kongskilde Industries"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kongskildegrain","https:\/\/www.linkedin.com\/company\/kongskilde-industries-a-s\/","https:\/\/www.youtube.com\/@kongskildeindustries"]},{"@type":"Person","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb","name":"breewunderlich"}]}},"_links":{"self":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/comments?post=81703"}],"version-history":[{"count":2,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81703\/revisions"}],"predecessor-version":[{"id":82798,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81703\/revisions\/82798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media\/81281"}],"wp:attachment":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media?parent=81703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/categories?post=81703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/tags?post=81703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":81577,"date":"2024-09-27T12:14:33","date_gmt":"2024-09-27T12:14:33","guid":{"rendered":"https:\/\/kongskilde-industries.com\/kongskilde-industries-afirma-su-compromiso-con-los-clientes-agricolas-en-medio-de-la-confusion-del-mercado\/"},"modified":"2026-04-07T10:33:34","modified_gmt":"2026-04-07T10:33:34","slug":"kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2","status":"publish","type":"post","link":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\/","title":{"rendered":"Kongskilde Industries reafirma su compromiso con los clientes agr\u00edcolas en medio de la confusi\u00f3n del mercado"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-celebrating-75-years-of-innovation-in-grain-handling-solutions\"><em>Celebrando 75 a\u00f1os de innovaci\u00f3n en soluciones para la manipulaci\u00f3n de granos<\/em><\/h2>\n\n<p><strong>Kongskilde Industries<\/strong>, proveedor l\u00edder de sistemas neum\u00e1ticos de manipulaci\u00f3n de granos, se complace en asegurar a sus clientes agr\u00edcolas su continua estabilidad y crecimiento, a pesar de los recientes acontecimientos que han afectado a Kongskilde. Tras la venta de Kongskilde a Seko Industries el 7 de agosto de 2024, deseamos aclarar que <strong>Kongskilde Industries<\/strong> sigue siendo una entidad completamente separada y no se ve afectada por la venta.<\/p>\n\n<p>Fundada originalmente en <strong>1949,<\/strong> la marca Kongskilde tiene una larga historia al servicio de la comunidad agr\u00edcola. En<strong> 2017<\/strong>, la empresa se dividi\u00f3 en dos entidades distintas: Kongskilde Industries, especializada en la manipulaci\u00f3n neum\u00e1tica de granos y sistemas industriales, y Kongskilde, que se centra en equipos de labranza y cultivo del suelo. Desde la divisi\u00f3n, Kongskilde Industries ha operado de forma independiente, y nuestro compromiso de apoyar a los agricultores con soluciones innovadoras para el manejo de granos sigue siendo tan fuerte como siempre al celebrar nuestro 75 aniversario.  <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-uninterrupted-service-and-support-for-farmers\"><strong>Servicio ininterrumpido y apoyo a los agricultores<\/strong><\/h3>\n\n<p>En <strong>Kongskilde Industries<\/strong>, nuestro enfoque en las soluciones de manipulaci\u00f3n de Grano sigue siendo m\u00e1s fuerte que nunca. El compromiso de la compa\u00f1\u00eda de apoyar a la comunidad agr\u00edcola con sistemas neum\u00e1ticos innovadores y fiables no ha cambiado. Nuestras l\u00edneas de productos est\u00e1n totalmente disponibles, y nuestros clientes pueden seguir confiando en el alto nivel de servicio y soporte que ha definido a Kongskilde Industries durante d\u00e9cadas.  <\/p>\n\n<p>\u00abEntendemos que la reciente venta de Kongskilde ha creado cierta confusi\u00f3n en el mercado, particularmente entre los agricultores que conf\u00edan en los sistemas de manipulaci\u00f3n de granos\u00bb, dijo Kim Johnsen, CCO de Kongskilde Industries. \u00abQueremos asegurar a nuestros clientes que <strong>Kongskilde Industries no se ve afectada por esta venta<\/strong>, y seguimos plenamente comprometidos a apoyar a la comunidad agr\u00edcola con tecnolog\u00eda l\u00edder en la industria de manejo de granos.\u00bb <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-a-legacy-of-innovation-75-years-of-agricultural-excellence\"><strong>Un legado de innovaci\u00f3n: 75 a\u00f1os de excelencia agr\u00edcola<\/strong><\/h3>\n\n<p>Este a\u00f1o se cumplen <strong>75<\/strong> a\u00f1os desde la fundaci\u00f3n de la marca Kongskilde original, y aunque Kongskilde se ha movido en una direcci\u00f3n diferente, <strong>Kongskilde Industries<\/strong> se enorgullece de llevar adelante el legado de innovaci\u00f3n agr\u00edcola a trav\u00e9s de sus sistemas neum\u00e1ticos de vanguardia. Nuestra divisi\u00f3n de Grano sigue centr\u00e1ndose en mejorar la eficiencia, la productividad y la facilidad de uso para los agricultores de todo el mundo. <\/p>\n\n<p>Como parte de las <strong>celebraciones del 75 aniversario<\/strong>, Kongskilde Industries lanzar\u00e1 nuevas iniciativas para resaltar nuestra historia y las futuras innovaciones en soluciones para el manejo de granos. Esperamos seguir sirviendo a la comunidad agr\u00edcola durante muchas d\u00e9cadas m\u00e1s. <\/p>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group has-palette-light-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading\" id=\"h-about-kongskilde-industries\">Acerca de <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-palette-brand-1-color\">Kongskilde Industries<\/mark><\/strong><\/h4>\n\n\n\n<p>Kongskilde Industries es l\u00edder mundial en sistemas neum\u00e1ticos para la manipulaci\u00f3n de Grano y aplicaciones Industriales. Fundada originalmente en 1949, la empresa se convirti\u00f3 en Kongskilde Industries en 2017 tras la divisi\u00f3n de la marca Kongskilde original. Kongskilde Industries se especializa en proporcionar soluciones innovadoras y fiables a los agricultores y fabricantes. Con 75 a\u00f1os de legado y experiencia, <strong>Kongskilde Industries<\/strong> contin\u00faa impulsando la innovaci\u00f3n y ofreciendo productos de alta calidad que satisfacen las necesidades cambiantes de sus clientes.   <\/p>\n<\/div><\/div>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<hr class=\"wp-block-separator has-text-color has-palette-light-color has-alpha-channel-opacity has-palette-light-background-color has-background is-style-wide\"\/>\n\n<h2 class=\"wp-block-heading\" id=\"h-faq\">PREGUNTAS FRECUENTES<\/h2>\n<div class=\"wp-block-ub-content-toggle wp-block-ub-content-toggle-block\" id=\"ub-content-toggle-block-676ab6de-9ef3-4ed4-8a25-5e33171bb6f1\" data-mobilecollapse=\"false\" data-desktopcollapse=\"false\" data-preventcollapse=\"true\" data-showonlyone=\"false\">\n<div class=\"wp-block-ub-content-toggle-accordion\" style=\"border-color: #f1f1f1; \" id=\"ub-content-toggle-panel-block-8df71509-1362-44ca-ad84-29e017a364f5\">\n\t\t\t<div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" style=\"background-color: #f1f1f1;\" aria-disabled=\"true\" aria-controls=\"ub-content-toggle-panel-0-676ab6de-9ef3-4ed4-8a25-5e33171bb6f1\" tabindex=\"0\">\n\t\t\t<p class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-676ab6de-9ef3-4ed4-8a25-5e33171bb6f1\" style=\"color: #0e1e63; \">P: <strong>\u00bfCu\u00e1l es la relaci\u00f3n entre Kongskilde y Kongskilde Industries?<\/strong><\/p>\n\t\t\t<div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\" style=\"color: #565656;\"><span class=\"wp-block-ub-content-toggle-accordion-state-indicator wp-block-ub-chevron-down open\"><\/span><\/div>\n\t\t<\/div>\n\t\t\t<div role=\"region\" aria-expanded=\"true\" class=\"wp-block-ub-content-toggle-accordion-content-wrap\" id=\"ub-content-toggle-panel-0-676ab6de-9ef3-4ed4-8a25-5e33171bb6f1\">\n\n<p>R: En 2017, Kongskilde se dividi\u00f3 en dos empresas separadas. <strong>Kongskilde Industries<\/strong> se centra en sistemas neum\u00e1ticos, especialmente para la manipulaci\u00f3n de granos y aplicaciones industriales, mientras que <strong>Kongskilde<\/strong>, que fue vendida a <strong>CNH Industrial<\/strong> en 2017, se centra en equipos de labranza y cultivo del suelo. <strong>Kongskilde<\/strong> fue vendida de nuevo recientemente por <strong>CNH Industrial a Seko Industries<\/strong> en 2024. <strong>Kongskilde Industries<\/strong> sigue siendo independiente y no se ve afectada por esta venta.<\/p>\n\n<\/div>\n\t\t<\/div>\n\n<div class=\"wp-block-ub-content-toggle-accordion\" style=\"border-color: #f1f1f1; \" id=\"ub-content-toggle-panel-block-8df71509-1362-44ca-ad84-29e017a364f5\">\n\t\t\t<div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" style=\"background-color: #f1f1f1;\" aria-disabled=\"true\" aria-controls=\"ub-content-toggle-panel-1-676ab6de-9ef3-4ed4-8a25-5e33171bb6f1\" tabindex=\"0\">\n\t\t\t<p class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-676ab6de-9ef3-4ed4-8a25-5e33171bb6f1\" style=\"color: #0e1e63; \"><strong>P: \u00bfAfecta la venta de Kongskilde a Seko Industries a Kongskilde Industries?<\/strong><\/p>\n\t\t\t<div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\" style=\"color: #565656;\"><span class=\"wp-block-ub-content-toggle-accordion-state-indicator wp-block-ub-chevron-down open\"><\/span><\/div>\n\t\t<\/div>\n\t\t\t<div role=\"region\" aria-expanded=\"true\" class=\"wp-block-ub-content-toggle-accordion-content-wrap\" id=\"ub-content-toggle-panel-1-676ab6de-9ef3-4ed4-8a25-5e33171bb6f1\">\n\n<p><strong>R:<\/strong> No, <strong>Kongskilde Industries<\/strong> no se ve afectada por esta venta. Seguimos operando de forma independiente y seguimos centrados en servir a los agricultores con soluciones fiables de manipulaci\u00f3n neum\u00e1tica de granos. <\/p>\n\n<\/div>\n\t\t<\/div>\n\n<div class=\"wp-block-ub-content-toggle-accordion\" style=\"border-color: #f1f1f1; \" id=\"ub-content-toggle-panel-block-\">\n\t\t\t<div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" style=\"background-color: #f1f1f1;\" aria-disabled=\"true\" aria-controls=\"ub-content-toggle-panel-2-676ab6de-9ef3-4ed4-8a25-5e33171bb6f1\" tabindex=\"0\">\n\t\t\t<p class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-676ab6de-9ef3-4ed4-8a25-5e33171bb6f1\" style=\"color: #0e1e63; \"><strong>P: \u00bfHay alg\u00fan cambio en la oferta de productos o servicios de Kongskilde Industries?<\/strong><\/p>\n\t\t\t<div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\" style=\"color: #565656;\"><span class=\"wp-block-ub-content-toggle-accordion-state-indicator wp-block-ub-chevron-down open\"><\/span><\/div>\n\t\t<\/div>\n\t\t\t<div role=\"region\" aria-expanded=\"true\" class=\"wp-block-ub-content-toggle-accordion-content-wrap\" id=\"ub-content-toggle-panel-2-676ab6de-9ef3-4ed4-8a25-5e33171bb6f1\">\n\n<p><strong>R:<\/strong> No, todos los productos y servicios <strong>de Kongskilde Industries<\/strong> est\u00e1n totalmente disponibles. Estamos comprometidos a ofrecer las mismas soluciones de manejo de granos de alta calidad y el apoyo que usted espera de nosotros. <\/p>\n\n<\/div>\n\t\t<\/div>\n<\/div>\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p><strong>Para m\u00e1s informaci\u00f3n<\/strong><\/p>\n\n<p>Para saber m\u00e1s sobre <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-palette-brand-3-color\">Kongskilde Industries<\/mark><\/strong> y nuestras soluciones neum\u00e1ticas para la manipulaci\u00f3n de granos, visite nuestras <a href=\"https:\/\/kongskilde-industries.com\/grain\/products\/\">p\u00e1ginas de productos<\/a> o p\u00f3ngase en contacto con nuestro equipo de atenci\u00f3n al cliente en <a href=\"mailto:grain@kongskilde-industries.com\">grain@kongskilde-industries.com.<\/a><\/p>\n\n<p>Para saber m\u00e1s sobre <mark style=\"background-color:rgba(0, 0, 0, 0);color:#d70000\" class=\"has-inline-color\"><strong>Agricultura de Kongskilde<\/strong><\/mark>visite su p\u00e1gina web en <a href=\"https:\/\/www.kongskilde.com\/in\/en\/en\/Agriculture%20\">https:\/\/www.kongskilde.com\/in\/en\/en\/Agriculture <\/a> <\/p>\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tras la venta de Kongskilde a Seko Industries el 7 de agosto de 2024, deseamos aclarar que Kongskilde Industries sigue siendo una entidad completamente separada y no se ve afectada por la venta.<\/p>\n","protected":false},"author":5,"featured_media":81576,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[385],"tags":[758],"class_list":["post-81577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-cereales","tag-noticias"],"acf":{"footer_cta_override":"default","remove_footer_margin":false,"footer_cta":{"background_image":null,"product_image":null,"heading":"","subheading":"","link":null,"link_secondary":null}},"featured_image_src":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-HQ-Aerial-View_Web.jpg","author_info":{"display_name":"breewunderlich","author_link":"https:\/\/kongskilde-industries.com\/es\/author\/breewunderlich\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kongskilde Industries reafirma su compromiso con los clientes agr\u00edcolas en medio de la confusi\u00f3n del mercado - Kongskilde Industries<\/title>\n<meta name=\"description\" content=\"Tras la venta de Kongskilde a Seko, Kongskilde Industries sigue siendo independiente, celebrando 75 a\u00f1os de innovaci\u00f3n en soluciones para la manipulaci\u00f3n de granos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kongskilde Industries reafirma su compromiso con los clientes agr\u00edcolas en medio de la confusi\u00f3n del mercado\" \/>\n<meta property=\"og:description\" content=\"Tras la venta de Kongskilde a Seko, Kongskilde Industries sigue siendo independiente, celebrando 75 a\u00f1os de innovaci\u00f3n en soluciones para la manipulaci\u00f3n de granos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Kongskilde Industries\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kongskildegrain\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-27T12:14:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T10:33:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-HQ-Aerial-View_Web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1145\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"breewunderlich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\\\/\"},\"author\":{\"name\":\"breewunderlich\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\"},\"headline\":\"Kongskilde Industries reafirma su compromiso con los clientes agr\u00edcolas en medio de la confusi\u00f3n del mercado\",\"datePublished\":\"2024-09-27T12:14:33+00:00\",\"dateModified\":\"2026-04-07T10:33:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\\\/\"},\"wordCount\":778,\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-HQ-Aerial-View_Web.jpg\",\"keywords\":[\"Noticias\"],\"articleSection\":[\"Noticias sobre el grano\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\\\/\",\"name\":\"Kongskilde Industries reafirma su compromiso con los clientes agr\u00edcolas en medio de la confusi\u00f3n del mercado - Kongskilde Industries\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-HQ-Aerial-View_Web.jpg\",\"datePublished\":\"2024-09-27T12:14:33+00:00\",\"dateModified\":\"2026-04-07T10:33:34+00:00\",\"description\":\"Tras la venta de Kongskilde a Seko, Kongskilde Industries sigue siendo independiente, celebrando 75 a\u00f1os de innovaci\u00f3n en soluciones para la manipulaci\u00f3n de granos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-HQ-Aerial-View_Web.jpg\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-HQ-Aerial-View_Web.jpg\",\"width\":2000,\"height\":1145},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kongskilde Industries reafirma su compromiso con los clientes agr\u00edcolas en medio de la confusi\u00f3n del mercado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"name\":\"Kongskilde Industries\",\"description\":\"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"alternateName\":\"Kongskilde\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\",\"name\":\"Kongskilde Industries\",\"alternateName\":\"Kongskilde\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"width\":2550,\"height\":392,\"caption\":\"Kongskilde Industries\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kongskildegrain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kongskilde-industries-a-s\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@kongskildeindustries\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\",\"name\":\"breewunderlich\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kongskilde Industries reafirma su compromiso con los clientes agr\u00edcolas en medio de la confusi\u00f3n del mercado - Kongskilde Industries","description":"Tras la venta de Kongskilde a Seko, Kongskilde Industries sigue siendo independiente, celebrando 75 a\u00f1os de innovaci\u00f3n en soluciones para la manipulaci\u00f3n de granos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Kongskilde Industries reafirma su compromiso con los clientes agr\u00edcolas en medio de la confusi\u00f3n del mercado","og_description":"Tras la venta de Kongskilde a Seko, Kongskilde Industries sigue siendo independiente, celebrando 75 a\u00f1os de innovaci\u00f3n en soluciones para la manipulaci\u00f3n de granos.","og_url":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\/","og_site_name":"Kongskilde Industries","article_publisher":"https:\/\/www.facebook.com\/kongskildegrain","article_published_time":"2024-09-27T12:14:33+00:00","article_modified_time":"2026-04-07T10:33:34+00:00","og_image":[{"width":2000,"height":1145,"url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-HQ-Aerial-View_Web.jpg","type":"image\/jpeg"}],"author":"breewunderlich","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\/#article","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\/"},"author":{"name":"breewunderlich","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb"},"headline":"Kongskilde Industries reafirma su compromiso con los clientes agr\u00edcolas en medio de la confusi\u00f3n del mercado","datePublished":"2024-09-27T12:14:33+00:00","dateModified":"2026-04-07T10:33:34+00:00","mainEntityOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\/"},"wordCount":778,"publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-HQ-Aerial-View_Web.jpg","keywords":["Noticias"],"articleSection":["Noticias sobre el grano"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\/","url":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\/","name":"Kongskilde Industries reafirma su compromiso con los clientes agr\u00edcolas en medio de la confusi\u00f3n del mercado - Kongskilde Industries","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\/#primaryimage"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-HQ-Aerial-View_Web.jpg","datePublished":"2024-09-27T12:14:33+00:00","dateModified":"2026-04-07T10:33:34+00:00","description":"Tras la venta de Kongskilde a Seko, Kongskilde Industries sigue siendo independiente, celebrando 75 a\u00f1os de innovaci\u00f3n en soluciones para la manipulaci\u00f3n de granos.","breadcrumb":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\/#primaryimage","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-HQ-Aerial-View_Web.jpg","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-HQ-Aerial-View_Web.jpg","width":2000,"height":1145},{"@type":"BreadcrumbList","@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-industries-reaffirms-commitment-to-agricultural-customers-amid-market-confusion-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kongskilde-industries.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Kongskilde Industries reafirma su compromiso con los clientes agr\u00edcolas en medio de la confusi\u00f3n del mercado"}]},{"@type":"WebSite","@id":"https:\/\/kongskilde-industries.com\/es\/#website","url":"https:\/\/kongskilde-industries.com\/es\/","name":"Kongskilde Industries","description":"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.","publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"alternateName":"Kongskilde","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kongskilde-industries.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kongskilde-industries.com\/es\/#organization","name":"Kongskilde Industries","alternateName":"Kongskilde","url":"https:\/\/kongskilde-industries.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","width":2550,"height":392,"caption":"Kongskilde Industries"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kongskildegrain","https:\/\/www.linkedin.com\/company\/kongskilde-industries-a-s\/","https:\/\/www.youtube.com\/@kongskildeindustries"]},{"@type":"Person","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb","name":"breewunderlich"}]}},"_links":{"self":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/comments?post=81577"}],"version-history":[{"count":5,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81577\/revisions"}],"predecessor-version":[{"id":82882,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81577\/revisions\/82882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media\/81576"}],"wp:attachment":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media?parent=81577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/categories?post=81577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/tags?post=81577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":81540,"date":"2024-09-04T06:16:33","date_gmt":"2024-09-04T06:16:33","guid":{"rendered":"https:\/\/kongskilde-industries.com\/nuevo-producto-cortadora-mcb\/"},"modified":"2026-04-07T10:33:33","modified_gmt":"2026-04-07T10:33:33","slug":"nuevo-producto-cortadora-mcb","status":"publish","type":"post","link":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cortadora-mcb\/","title":{"rendered":"NUEVO PRODUCTO &#8211; MultiCutter MCB"},"content":{"rendered":"\n<div style=\"height:2px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-cover\" style=\"min-height:200px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-palette-brand-1-background-color has-background-dim\"><\/span><img decoding=\"async\" class=\"wp-block-cover__image-background wp-image-81289\" alt=\"\" src=\"https:\/\/kongskilde-industries.com\/industrial\/wp-content\/uploads\/sites\/3\/MCB-Cutter-maintenance_web.jpg\" data-object-fit=\"cover\"\/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size\"><\/p>\n<\/div><\/div>\n\n<div class=\"wp-block-columns is-style-xl-gutter is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading\" id=\"h-introducing-the-multicutter-mcb\">Presentaci\u00f3n de la <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-palette-brand-4-color\">MultiCutter MCB <\/mark> <\/h2>\n\n\n\n<p>Nos complace anunciar la incorporaci\u00f3n de la serie de cortadoras MCB a nuestra l\u00ednea de cortadoras y granuladoras de tama\u00f1o reducido en Kongskilde. Estas vanguardistas unidades en l\u00ednea est\u00e1n dise\u00f1adas para procesar eficientemente materiales de desecho continuos e interminables, lo que las convierte en un valioso activo para las industrias que buscan mejorar su gesti\u00f3n de residuos y su eficiencia operativa. <\/p>\n\n\n\n<p><strong>Integraci\u00f3n perfecta para mejorar el rendimiento<\/strong><\/p>\n\n\n\n<p>Nuestras MultiCutters MCB se integran a la perfecci\u00f3n en los sistemas de extracci\u00f3n de residuos, tanto nuevos como ya existentes, garantizando un rendimiento \u00f3ptimo en diversos sectores, como el envasado, la producci\u00f3n de etiquetas y la impresi\u00f3n. Estas cortadoras son muy eficaces en el procesado de materiales como papel, cart\u00f3n, pl\u00e1sticos flexibles y papel de aluminio, proporcionando una soluci\u00f3n ideal para las empresas que buscan optimizar sus procesos de gesti\u00f3n de residuos. <\/p>\n\n\n\n<p><strong>Capacidades vers\u00e1tiles de manipulaci\u00f3n de residuos<\/strong><\/p>\n\n\n\n<p>Las cortadoras MCB est\u00e1n dise\u00f1adas pensando en la versatilidad y la fiabilidad, y son capaces de manipular una amplia gama de materiales con una resistencia al aire m\u00ednima y un alto rendimiento. Equipadas con 2 \u00f3 3 cuchillas giratorias y una cuchilla fija, estas cortadoras garantizan un corte preciso y eficaz de los materiales residuales de producci\u00f3n, como tiras de canto y rejillas estampadas. <\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-style-rounded has-palette-light-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/kongskilde-industries.com\/industrial\/wp-content\/uploads\/sites\/3\/MCB-Cutter_Transparent_web.png\" alt=\"\" class=\"wp-image-81282\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-center has-palette-brand-1-color has-text-color has-link-color wp-elements-c8632a6361c58bac233ee65d2c15b192\"><strong>Explore las caracter\u00edsticas y compare los modelos para la MultiCutter MCB<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-align-center wp-element-button\" href=\"https:\/\/kongskilde-industries.com\/industrial\/product\/mcb-cutter\/\">M\u00e1s informaci\u00f3n  <\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-group has-palette-light-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"h-key-features\"><strong>Caracter\u00edsticas principales:<\/strong><\/h3>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/3\/16\/2714.png\" alt=\"&#x2714;&#xFE0F;\"\/> <strong>Gran reducci\u00f3n del volumen de residuos:<\/strong> Disminuye significativamente el volumen de residuos de producci\u00f3n.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/3\/16\/2714.png\" alt=\"&#x2714;&#xFE0F;\"\/> <strong> Capacidad de corte vers\u00e1til: <\/strong>Capaz de cortar una amplia gama de materiales.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/3\/16\/2714.png\" alt=\"&#x2714;&#xFE0F;\"\/> <strong> Dise\u00f1o compacto: <\/strong>Optimizado para ahorrar espacio de instalaci\u00f3n.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/3\/16\/2714.png\" alt=\"&#x2714;&#xFE0F;\"\/> <strong>Aut\u00e9ntico corte de tijera:<\/strong> Garantiza cortes precisos y limpios.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/3\/16\/2714.png\" alt=\"&#x2714;&#xFE0F;\"\/> <strong>Funcionamiento silencioso:<\/strong> El principio de corte en tijera garantiza un funcionamiento silencioso.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/3\/16\/2714.png\" alt=\"&#x2714;&#xFE0F;\"\/> <strong>Alto rendimiento:<\/strong> Mantiene altas velocidades de procesamiento.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/3\/16\/2714.png\" alt=\"&#x2714;&#xFE0F;\"\/> <strong>Bajo consumo energ\u00e9tico:<\/strong> Dise\u00f1o de bajo consumo.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/3\/16\/2714.png\" alt=\"&#x2714;&#xFE0F;\"\/> <strong> Baja resistencia al aire: <\/strong>Minimiza el impacto en el flujo de aire dentro de los sistemas de extracci\u00f3n.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/3\/16\/2714.png\" alt=\"&#x2714;&#xFE0F;\"\/> <strong> Bajos costes de funcionamiento:<\/strong> Mantenimiento y funcionamiento rentables.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/3\/16\/2714.png\" alt=\"&#x2714;&#xFE0F;\"\/> <strong> Colocaci\u00f3n flexible:<\/strong> La cortadora puede montarse en cualquier direcci\u00f3n.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"is-style-cta-link\"><a href=\"https:\/\/kongskilde-industries.com\/industrial\/product\/mcb-cutter\/\" data-type=\"link\" data-id=\"https:\/\/kongskilde-industries.com\/industrial\/product\/mcb-cutter\/\">M\u00e1s informaci\u00f3n sobre la cortadora MCB<\/a><\/p>\n<\/div><\/div>\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nos complace anunciar la incorporaci\u00f3n de la serie de cortadoras MCB a nuestra l\u00ednea de cortadoras y granuladoras de tama\u00f1o reducido en Kongskilde.  <\/p>\n","protected":false},"author":5,"featured_media":81538,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[150],"tags":[758],"class_list":["post-81540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-industriales","tag-noticias"],"acf":{"footer_cta_override":"default","remove_footer_margin":false,"footer_cta":{"background_image":null,"product_image":null,"heading":"","subheading":"","link":null,"link_secondary":null}},"featured_image_src":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MCB-Cutter-Featured-Image.jpg","author_info":{"display_name":"breewunderlich","author_link":"https:\/\/kongskilde-industries.com\/es\/author\/breewunderlich\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NUEVO PRODUCTO - MultiCutter MCB - Kongskilde Industries<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUEVO PRODUCTO - MultiCutter MCB\" \/>\n<meta property=\"og:description\" content=\"Nos complace anunciar la incorporaci\u00f3n de la serie de cortadoras MCB a nuestra l\u00ednea de cortadoras y granuladoras de tama\u00f1o reducido en Kongskilde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cortadora-mcb\/\" \/>\n<meta property=\"og:site_name\" content=\"Kongskilde Industries\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kongskildegrain\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-04T06:16:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T10:33:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MCB-Cutter-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"breewunderlich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cortadora-mcb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cortadora-mcb\\\/\"},\"author\":{\"name\":\"breewunderlich\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\"},\"headline\":\"NUEVO PRODUCTO &#8211; MultiCutter MCB\",\"datePublished\":\"2024-09-04T06:16:33+00:00\",\"dateModified\":\"2026-04-07T10:33:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cortadora-mcb\\\/\"},\"wordCount\":381,\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cortadora-mcb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/MCB-Cutter-Featured-Image.jpg\",\"keywords\":[\"Noticias\"],\"articleSection\":[\"Noticias Industriales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cortadora-mcb\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cortadora-mcb\\\/\",\"name\":\"NUEVO PRODUCTO - MultiCutter MCB - Kongskilde Industries\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cortadora-mcb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cortadora-mcb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/MCB-Cutter-Featured-Image.jpg\",\"datePublished\":\"2024-09-04T06:16:33+00:00\",\"dateModified\":\"2026-04-07T10:33:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cortadora-mcb\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cortadora-mcb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cortadora-mcb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/MCB-Cutter-Featured-Image.jpg\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/MCB-Cutter-Featured-Image.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cortadora-mcb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUEVO PRODUCTO &#8211; MultiCutter MCB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"name\":\"Kongskilde Industries\",\"description\":\"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"alternateName\":\"Kongskilde\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\",\"name\":\"Kongskilde Industries\",\"alternateName\":\"Kongskilde\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"width\":2550,\"height\":392,\"caption\":\"Kongskilde Industries\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kongskildegrain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kongskilde-industries-a-s\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@kongskildeindustries\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\",\"name\":\"breewunderlich\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NUEVO PRODUCTO - MultiCutter MCB - Kongskilde Industries","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"NUEVO PRODUCTO - MultiCutter MCB","og_description":"Nos complace anunciar la incorporaci\u00f3n de la serie de cortadoras MCB a nuestra l\u00ednea de cortadoras y granuladoras de tama\u00f1o reducido en Kongskilde.","og_url":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cortadora-mcb\/","og_site_name":"Kongskilde Industries","article_publisher":"https:\/\/www.facebook.com\/kongskildegrain","article_published_time":"2024-09-04T06:16:33+00:00","article_modified_time":"2026-04-07T10:33:33+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MCB-Cutter-Featured-Image.jpg","type":"image\/jpeg"}],"author":"breewunderlich","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cortadora-mcb\/#article","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cortadora-mcb\/"},"author":{"name":"breewunderlich","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb"},"headline":"NUEVO PRODUCTO &#8211; MultiCutter MCB","datePublished":"2024-09-04T06:16:33+00:00","dateModified":"2026-04-07T10:33:33+00:00","mainEntityOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cortadora-mcb\/"},"wordCount":381,"publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cortadora-mcb\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MCB-Cutter-Featured-Image.jpg","keywords":["Noticias"],"articleSection":["Noticias Industriales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cortadora-mcb\/","url":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cortadora-mcb\/","name":"NUEVO PRODUCTO - MultiCutter MCB - Kongskilde Industries","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cortadora-mcb\/#primaryimage"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cortadora-mcb\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MCB-Cutter-Featured-Image.jpg","datePublished":"2024-09-04T06:16:33+00:00","dateModified":"2026-04-07T10:33:33+00:00","breadcrumb":{"@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cortadora-mcb\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cortadora-mcb\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cortadora-mcb\/#primaryimage","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MCB-Cutter-Featured-Image.jpg","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/MCB-Cutter-Featured-Image.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cortadora-mcb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kongskilde-industries.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"NUEVO PRODUCTO &#8211; MultiCutter MCB"}]},{"@type":"WebSite","@id":"https:\/\/kongskilde-industries.com\/es\/#website","url":"https:\/\/kongskilde-industries.com\/es\/","name":"Kongskilde Industries","description":"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.","publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"alternateName":"Kongskilde","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kongskilde-industries.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kongskilde-industries.com\/es\/#organization","name":"Kongskilde Industries","alternateName":"Kongskilde","url":"https:\/\/kongskilde-industries.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","width":2550,"height":392,"caption":"Kongskilde Industries"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kongskildegrain","https:\/\/www.linkedin.com\/company\/kongskilde-industries-a-s\/","https:\/\/www.youtube.com\/@kongskildeindustries"]},{"@type":"Person","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb","name":"breewunderlich"}]}},"_links":{"self":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/comments?post=81540"}],"version-history":[{"count":2,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81540\/revisions"}],"predecessor-version":[{"id":82880,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81540\/revisions\/82880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media\/81538"}],"wp:attachment":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media?parent=81540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/categories?post=81540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/tags?post=81540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":81350,"date":"2024-02-02T19:05:51","date_gmt":"2024-02-02T19:05:51","guid":{"rendered":"https:\/\/kongskilde-industries.com\/nuevo-producto-cubo-todo-en-una-unidad\/"},"modified":"2026-04-07T10:33:18","modified_gmt":"2026-04-07T10:33:18","slug":"nuevo-producto-cubo-todo-en-una-unidad","status":"publish","type":"post","link":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cubo-todo-en-una-unidad\/","title":{"rendered":"NUEVO PRODUCTO &#8211; Kongskilde CUB Unidad todo en uno"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1833\" height=\"406\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Compact-Unit-banner-2.png\" alt=\"\" class=\"wp-image-81329\" srcset=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Compact-Unit-banner-2.png 1833w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Compact-Unit-banner-2-600x133.png 600w\" sizes=\"auto, (max-width: 1833px) 100vw, 1833px\" \/><\/figure>\n\n<div style=\"height:2px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-columns is-style-xl-gutter is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading\" id=\"h-introducing-the-cub-all-in-one-unit\">Presentaci\u00f3n de la <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-palette-brand-4-color\">unidad CUB todo en uno<\/mark><\/h2>\n\n\n\n<p>Kongskilde se complace en presentar la unidad todo en uno de la serie CUB, una soluci\u00f3n de vanguardia para la manipulaci\u00f3n de recortes de bordes no adhesivos o autoadhesivos, piezas troqueladas y matrices.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-a-compact-machine-side-waste-collection-unit-for-process-waste\"><strong>Una unidad compacta de recogida de residuos de m\u00e1quinas para residuos de procesos<\/strong><\/h4>\n\n\n\n<p>Mejore sus procesos de fabricaci\u00f3n optimiz\u00e1ndolos con nuestra unidad de vanguardia. Espec\u00edficamente dise\u00f1ado para manipular en una misma l\u00ednea de producci\u00f3n tanto recortes de bordes no adhesivos como autoadhesivos, piezas troqueladas y matrices, este sistema no s\u00f3lo es extremadamente compacto sino tambi\u00e9n de fabricaci\u00f3n robusta. Su dise\u00f1o permite un f\u00e1cil desplazamiento entre m\u00e1quinas.<\/p>\n\n\n\n<p>Adem\u00e1s, este vers\u00e1til sistema puede adaptarse a\u00fan m\u00e1s a sus necesidades espec\u00edficas. Considere la posibilidad de personalizarlo con un sistema integrado de separaci\u00f3n de materiales, especialmente beneficioso para los procesos de reciclaje cuando sea necesario. Esta caracter\u00edstica a\u00f1adida garantiza un flujo de producci\u00f3n fluido y eficaz, contribuyendo a una experiencia general de fabricaci\u00f3n optimizada.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-style-rounded\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-palette-brand-1-color has-text-color has-link-color wp-elements-f9583325490a902357d0cdad4063acb0\"><strong>Explore las caracter\u00edsticas, compare modelos, descargue documentaci\u00f3n y vea v\u00eddeos del CUB en acci\u00f3n.<\/strong><\/p>\n\n\n\n<p class=\"is-style-cta-link\"><a href=\"https:\/\/kongskilde-industries.com\/industrial\/product\/compact-unit-cub\/\">M\u00e1s informaci\u00f3n sobre la nueva unidad CUB todo en uno<\/a><\/p>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"wp-block-image-slider alignnone contain\">    <ul id=\"imageSlider\" class=\"gallery lightSlider\">\n    <li data-thumb=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-Tech-Center_Edited_With-New-Label-scaled.jpg\" data-src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-Tech-Center_Edited_With-New-Label-scaled.jpg\" class=\"has-caption contain\"><img loading=\"lazy\" decoding=\"async\" width=\"1905\" height=\"2560\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-Tech-Center_Edited_With-New-Label-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-Tech-Center_Edited_With-New-Label-scaled.jpg 1905w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-Tech-Center_Edited_With-New-Label-447x600.jpg 447w\" sizes=\"auto, (max-width: 1905px) 100vw, 1905px\" \/><figcaption>Unidad compacta CUB<\/figcaption><\/li><li data-thumb=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/3.-DSC_0669_edited_webop.jpg\" data-src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/3.-DSC_0669_edited_webop.jpg\" ><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1179\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/3.-DSC_0669_edited_webop.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/3.-DSC_0669_edited_webop.jpg 1600w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/3.-DSC_0669_edited_webop-600x442.jpg 600w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/li><li data-thumb=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Control-panel-CUB_lowres_edited_web.jpg\" data-src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Control-panel-CUB_lowres_edited_web.jpg\" class=\"has-caption contain\"><img loading=\"lazy\" decoding=\"async\" width=\"868\" height=\"668\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Control-panel-CUB_lowres_edited_web.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Control-panel-CUB_lowres_edited_web.jpg 868w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Control-panel-CUB_lowres_edited_web-600x462.jpg 600w\" sizes=\"auto, (max-width: 868px) 100vw, 868px\" \/><figcaption>Controles sencillos con pulsador y selector r\u00e1pido<\/figcaption><\/li><\/ul><\/div><\/div>\n<\/div>\n\n<div class=\"wp-block-group has-palette-light-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"h-key-features\"><strong>Caracter\u00edsticas principales:<\/strong><\/h3>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/3\/16\/2714.png\" alt=\"&#x2714;&#xFE0F;\"\/> <strong>Funcionamiento silencioso, m\u00e1ximo impacto:<\/strong> El CUB funciona silenciosamente, alojado dentro de una caja de acero sellada con grandes silenciadores. Sin interrupciones, \u00a1s\u00f3lo pura eficacia en su entorno de producci\u00f3n!<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/3\/16\/2714.png\" alt=\"&#x2714;&#xFE0F;\"\/> <strong>Mu\u00e9vase con facilidad, a cualquier lugar: <\/strong>El elegante dise\u00f1o del CUB permite moverlo f\u00e1cilmente con una carretilla elevadora o transpaleta, pasando sin esfuerzo por la mayor\u00eda de las puertas de las f\u00e1bricas. Ad\u00e1ptese a su espacio con una anchura de s\u00f3lo 800 mm y una altura de 2150 mm.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/3\/16\/2714.png\" alt=\"&#x2714;&#xFE0F;\"\/> <strong>Control intuitivo al alcance de su mano: <\/strong>Sin complejos PLC ni HMI: s\u00f3lo pulsadores sencillos y una marcaci\u00f3n r\u00e1pida. Opere con facilidad y precisi\u00f3n, mejorando su flujo de trabajo sin complicaciones innecesarias.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/3\/16\/2714.png\" alt=\"&#x2714;&#xFE0F;\"\/> <strong> Funcionamiento prolongado:<\/strong> Con una enorme capacidad de bolsa de 900 litros, disfrute de tiempos de funcionamiento prolongados entre cambios de bolsa. \u00bfNecesita acci\u00f3n sin parar? Nuestro kit de bolsas sin fin, selladas con bridas, mantiene su flujo de trabajo sin fisuras.<\/p>\n\n\n\n<p class=\"is-style-cta-link\"><a href=\"https:\/\/kongskilde-industries.com\/industrial\/product\/compact-unit-cub\/\">Explore todas las ventajas<\/a><\/p>\n<\/div><\/div>\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Kongskilde se complace en presentar la unidad todo en uno de la serie CUB, una soluci\u00f3n de vanguardia para la manipulaci\u00f3n de recortes de bordes no adhesivos o autoadhesivos, piezas troqueladas y matrices.<\/p>\n","protected":false},"author":5,"featured_media":81314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[150],"tags":[758],"class_list":["post-81350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-industriales","tag-noticias"],"acf":{"footer_cta_override":"default","remove_footer_margin":false,"footer_cta":{"background_image":null,"product_image":null,"heading":"","subheading":"","link":null,"link_secondary":null}},"featured_image_src":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-Tech-Center_Edited_With-New-Label-scaled.jpg","author_info":{"display_name":"breewunderlich","author_link":"https:\/\/kongskilde-industries.com\/es\/author\/breewunderlich\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NUEVO PRODUCTO - Kongskilde CUB Unidad todo en uno - Kongskilde Industries<\/title>\n<meta name=\"description\" content=\"Kongskilde se complace en presentar la unidad todo en uno de la serie CUB, una soluci\u00f3n de vanguardia para la manipulaci\u00f3n de recortes de bordes no adhesivos o autoadhesivos, piezas troqueladas y matrices.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUEVO PRODUCTO - Kongskilde CUB Unidad todo en uno\" \/>\n<meta property=\"og:description\" content=\"Kongskilde se complace en presentar la unidad todo en uno de la serie CUB, una soluci\u00f3n de vanguardia para la manipulaci\u00f3n de recortes de bordes no adhesivos o autoadhesivos, piezas troqueladas y matrices.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cubo-todo-en-una-unidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Kongskilde Industries\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kongskildegrain\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-02T19:05:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T10:33:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-Tech-Center_Edited_With-New-Label-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1905\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"breewunderlich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cubo-todo-en-una-unidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cubo-todo-en-una-unidad\\\/\"},\"author\":{\"name\":\"breewunderlich\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\"},\"headline\":\"NUEVO PRODUCTO &#8211; Kongskilde CUB Unidad todo en uno\",\"datePublished\":\"2024-02-02T19:05:51+00:00\",\"dateModified\":\"2026-04-07T10:33:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cubo-todo-en-una-unidad\\\/\"},\"wordCount\":396,\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cubo-todo-en-una-unidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/CUB-Tech-Center_Edited_With-New-Label-scaled.jpg\",\"keywords\":[\"Noticias\"],\"articleSection\":[\"Noticias Industriales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cubo-todo-en-una-unidad\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cubo-todo-en-una-unidad\\\/\",\"name\":\"NUEVO PRODUCTO - Kongskilde CUB Unidad todo en uno - Kongskilde Industries\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cubo-todo-en-una-unidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cubo-todo-en-una-unidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/CUB-Tech-Center_Edited_With-New-Label-scaled.jpg\",\"datePublished\":\"2024-02-02T19:05:51+00:00\",\"dateModified\":\"2026-04-07T10:33:18+00:00\",\"description\":\"Kongskilde se complace en presentar la unidad todo en uno de la serie CUB, una soluci\u00f3n de vanguardia para la manipulaci\u00f3n de recortes de bordes no adhesivos o autoadhesivos, piezas troqueladas y matrices.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cubo-todo-en-una-unidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cubo-todo-en-una-unidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cubo-todo-en-una-unidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/CUB-Tech-Center_Edited_With-New-Label-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/CUB-Tech-Center_Edited_With-New-Label-scaled.jpg\",\"width\":1905,\"height\":2560,\"caption\":\"Unidad compacta CUB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/nuevo-producto-cubo-todo-en-una-unidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUEVO PRODUCTO &#8211; Kongskilde CUB Unidad todo en uno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"name\":\"Kongskilde Industries\",\"description\":\"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"alternateName\":\"Kongskilde\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\",\"name\":\"Kongskilde Industries\",\"alternateName\":\"Kongskilde\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"width\":2550,\"height\":392,\"caption\":\"Kongskilde Industries\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kongskildegrain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kongskilde-industries-a-s\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@kongskildeindustries\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\",\"name\":\"breewunderlich\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NUEVO PRODUCTO - Kongskilde CUB Unidad todo en uno - Kongskilde Industries","description":"Kongskilde se complace en presentar la unidad todo en uno de la serie CUB, una soluci\u00f3n de vanguardia para la manipulaci\u00f3n de recortes de bordes no adhesivos o autoadhesivos, piezas troqueladas y matrices.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"NUEVO PRODUCTO - Kongskilde CUB Unidad todo en uno","og_description":"Kongskilde se complace en presentar la unidad todo en uno de la serie CUB, una soluci\u00f3n de vanguardia para la manipulaci\u00f3n de recortes de bordes no adhesivos o autoadhesivos, piezas troqueladas y matrices.","og_url":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cubo-todo-en-una-unidad\/","og_site_name":"Kongskilde Industries","article_publisher":"https:\/\/www.facebook.com\/kongskildegrain","article_published_time":"2024-02-02T19:05:51+00:00","article_modified_time":"2026-04-07T10:33:18+00:00","og_image":[{"width":1905,"height":2560,"url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-Tech-Center_Edited_With-New-Label-scaled.jpg","type":"image\/jpeg"}],"author":"breewunderlich","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cubo-todo-en-una-unidad\/#article","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cubo-todo-en-una-unidad\/"},"author":{"name":"breewunderlich","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb"},"headline":"NUEVO PRODUCTO &#8211; Kongskilde CUB Unidad todo en uno","datePublished":"2024-02-02T19:05:51+00:00","dateModified":"2026-04-07T10:33:18+00:00","mainEntityOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cubo-todo-en-una-unidad\/"},"wordCount":396,"publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cubo-todo-en-una-unidad\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-Tech-Center_Edited_With-New-Label-scaled.jpg","keywords":["Noticias"],"articleSection":["Noticias Industriales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cubo-todo-en-una-unidad\/","url":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cubo-todo-en-una-unidad\/","name":"NUEVO PRODUCTO - Kongskilde CUB Unidad todo en uno - Kongskilde Industries","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cubo-todo-en-una-unidad\/#primaryimage"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cubo-todo-en-una-unidad\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-Tech-Center_Edited_With-New-Label-scaled.jpg","datePublished":"2024-02-02T19:05:51+00:00","dateModified":"2026-04-07T10:33:18+00:00","description":"Kongskilde se complace en presentar la unidad todo en uno de la serie CUB, una soluci\u00f3n de vanguardia para la manipulaci\u00f3n de recortes de bordes no adhesivos o autoadhesivos, piezas troqueladas y matrices.","breadcrumb":{"@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cubo-todo-en-una-unidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cubo-todo-en-una-unidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cubo-todo-en-una-unidad\/#primaryimage","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-Tech-Center_Edited_With-New-Label-scaled.jpg","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/CUB-Tech-Center_Edited_With-New-Label-scaled.jpg","width":1905,"height":2560,"caption":"Unidad compacta CUB"},{"@type":"BreadcrumbList","@id":"https:\/\/kongskilde-industries.com\/es\/nuevo-producto-cubo-todo-en-una-unidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kongskilde-industries.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"NUEVO PRODUCTO &#8211; Kongskilde CUB Unidad todo en uno"}]},{"@type":"WebSite","@id":"https:\/\/kongskilde-industries.com\/es\/#website","url":"https:\/\/kongskilde-industries.com\/es\/","name":"Kongskilde Industries","description":"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.","publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"alternateName":"Kongskilde","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kongskilde-industries.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kongskilde-industries.com\/es\/#organization","name":"Kongskilde Industries","alternateName":"Kongskilde","url":"https:\/\/kongskilde-industries.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","width":2550,"height":392,"caption":"Kongskilde Industries"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kongskildegrain","https:\/\/www.linkedin.com\/company\/kongskilde-industries-a-s\/","https:\/\/www.youtube.com\/@kongskildeindustries"]},{"@type":"Person","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb","name":"breewunderlich"}]}},"_links":{"self":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/comments?post=81350"}],"version-history":[{"count":1,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81350\/revisions"}],"predecessor-version":[{"id":82618,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81350\/revisions\/82618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media\/81314"}],"wp:attachment":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media?parent=81350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/categories?post=81350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/tags?post=81350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":81285,"date":"2024-01-08T21:41:02","date_gmt":"2024-01-08T21:41:02","guid":{"rendered":"https:\/\/kongskilde-industries.com\/celebrando-75-anos-de-excelencia\/"},"modified":"2026-04-07T10:21:29","modified_gmt":"2026-04-07T10:21:29","slug":"celebrando-75-anos-de-excelencia","status":"publish","type":"post","link":"https:\/\/kongskilde-industries.com\/es\/celebrando-75-anos-de-excelencia\/","title":{"rendered":"Celebrando 75 a\u00f1os de excelencia"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1584\" height=\"396\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/LinkedIn-75-Years-Banner.jpg\" alt=\"\" class=\"wp-image-81268\" srcset=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/LinkedIn-75-Years-Banner.jpg 1584w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/LinkedIn-75-Years-Banner-600x150.jpg 600w\" sizes=\"auto, (max-width: 1584px) 100vw, 1584px\" \/><\/figure>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading\" id=\"h-2024-marks-a-remarkable-milestone-for-kongskilde-industries-our-nbsp-75th-anniversary-nbsp\"><strong>2024 marca un hito notable para Kongskilde Industries&#8230; \u00a1nuestro 75 aniversario!<\/strong> <\/h2>\n\n\n\n<p class=\"has-medium-font-size\">En 1949, la visi\u00f3n innovadora del Sr. Petersen y el Sr. Tyndeskov allan\u00f3 el camino para la creaci\u00f3n de nuestra empresa. Desde aquel humilde comienzo en un peque\u00f1o pueblo cerca de Copenhague, hemos evolucionado hasta convertirnos en un l\u00edder mundial en tecnolog\u00eda neum\u00e1tica.  <\/p>\n\n\n\n<p class=\"has-medium-font-size\">Al celebrar 75 a\u00f1os de innovaci\u00f3n, reflexionamos sobre nuestra trayectoria: desde la venta de ventiladores desde un coche hasta el establecimiento de oficinas de venta en todos los continentes. Nuestro compromiso con la excelencia se mantiene firme, y nuestra tecnolog\u00eda sigue simplificando los procesos e impulsando la eficiencia.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Extendemos nuestra gratitud a cada miembro del equipo, cliente y socio que ha formado parte de este incre\u00edble viaje. \u00a1Brindemos por 75 a\u00f1os de \u00e9xito, crecimiento y avances pioneros!<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>\u00danase a nosotros en las redes sociales para echar un vistazo a la emoci\u00f3n con la que conmemoramos \u00a175 a\u00f1os de excelencia!<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size has-medium-font-size\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/kongskilde-industries.com\/es\/redes-sociales\/\">S\u00edganos en las redes sociales<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-group is-style-rounded has-palette-light-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"8334\" height=\"6251\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Year-Kongskilde-Logo-Finals-03.png\" alt=\"\" class=\"wp-image-81254\" srcset=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Year-Kongskilde-Logo-Finals-03.png 8334w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Year-Kongskilde-Logo-Finals-03-600x450.png 600w\" sizes=\"auto, (max-width: 8334px) 100vw, 8334px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>Conozca m\u00e1s sobre la historia de Kongskilde en nuestra p\u00e1gina Qui\u00e9nes somos<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--5\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/kongskilde-industries.com\/es\/sobre\/\" target=\"_blank\" rel=\"noreferrer noopener\">M\u00e1s informaci\u00f3n<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-cover alignfull is-light\" style=\"min-height:150px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-palette-bg-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-columns no-padding has-palette-light-background-color has-background is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column negative-margin-top negative-margin-bottom is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:55%\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"The Kongskilde Industries Story\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/ZMomr3zfPu8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center padding-20 is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-palette-brand-1-color has-text-color\" id=\"h-our-story\">Nuestra historia<\/h2>\n\n\n\n<p style=\"font-style:normal;font-weight:400\">Vea la <a href=\"https:\/\/youtu.be\/ZMomr3zfPu8\"><strong>Historia de Kongskilde Industries<\/strong> <\/a>para ver c\u00f3mo empez\u00f3 todo en 1949 y c\u00f3mo seguimos proporcionando tecnolog\u00eda neum\u00e1tica y soluciones de transporte de confianza en todo el mundo.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>2024 marca un hito notable para Kongskilde Industries&#8230; \u00a1nuestro 75 aniversario! En 1949, la visi\u00f3n innovadora del Sr. Petersen y el Sr. Tyndeskov allan\u00f3 el camino para la creaci\u00f3n de nuestra empresa. Desde aquel humilde comienzo en un peque\u00f1o pueblo cerca de Copenhague, hemos evolucionado hasta convertirnos en un l\u00edder [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":81281,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[150,385],"tags":[758],"class_list":["post-81285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-industriales","category-noticias-cereales","tag-noticias"],"acf":{"footer_cta_override":"default","remove_footer_margin":false,"footer_cta":{"background_image":null,"product_image":null,"heading":"","subheading":"","link":null,"link_secondary":null}},"featured_image_src":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Anniversary-Cover.jpg","author_info":{"display_name":"breewunderlich","author_link":"https:\/\/kongskilde-industries.com\/es\/author\/breewunderlich\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Celebrando 75 a\u00f1os de excelencia - Kongskilde Industries<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebrando 75 a\u00f1os de excelencia\" \/>\n<meta property=\"og:description\" content=\"2024 marca un hito notable para Kongskilde Industries&#8230; \u00a1nuestro 75 aniversario! En 1949, la visi\u00f3n innovadora del Sr. Petersen y el Sr. Tyndeskov allan\u00f3 el camino para la creaci\u00f3n de nuestra empresa. Desde aquel humilde comienzo en un peque\u00f1o pueblo cerca de Copenhague, hemos evolucionado hasta convertirnos en un l\u00edder [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kongskilde-industries.com\/es\/celebrando-75-anos-de-excelencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Kongskilde Industries\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kongskildegrain\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-08T21:41:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T10:21:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Anniversary-Cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"breewunderlich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/celebrando-75-anos-de-excelencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/celebrando-75-anos-de-excelencia\\\/\"},\"author\":{\"name\":\"breewunderlich\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\"},\"headline\":\"Celebrando 75 a\u00f1os de excelencia\",\"datePublished\":\"2024-01-08T21:41:02+00:00\",\"dateModified\":\"2026-04-07T10:21:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/celebrando-75-anos-de-excelencia\\\/\"},\"wordCount\":229,\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/celebrando-75-anos-de-excelencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/75-Anniversary-Cover.jpg\",\"keywords\":[\"Noticias\"],\"articleSection\":[\"Noticias Industriales\",\"Noticias sobre el grano\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/celebrando-75-anos-de-excelencia\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/celebrando-75-anos-de-excelencia\\\/\",\"name\":\"Celebrando 75 a\u00f1os de excelencia - Kongskilde Industries\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/celebrando-75-anos-de-excelencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/celebrando-75-anos-de-excelencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/75-Anniversary-Cover.jpg\",\"datePublished\":\"2024-01-08T21:41:02+00:00\",\"dateModified\":\"2026-04-07T10:21:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/celebrando-75-anos-de-excelencia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/celebrando-75-anos-de-excelencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/celebrando-75-anos-de-excelencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/75-Anniversary-Cover.jpg\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/75-Anniversary-Cover.jpg\",\"width\":2000,\"height\":1500,\"caption\":\"75 Kongskilde 1949 - 2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/celebrando-75-anos-de-excelencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebrando 75 a\u00f1os de excelencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"name\":\"Kongskilde Industries\",\"description\":\"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"alternateName\":\"Kongskilde\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\",\"name\":\"Kongskilde Industries\",\"alternateName\":\"Kongskilde\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"width\":2550,\"height\":392,\"caption\":\"Kongskilde Industries\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kongskildegrain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kongskilde-industries-a-s\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@kongskildeindustries\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/e5a01ab01b55e978a1009059d5725fcb\",\"name\":\"breewunderlich\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Celebrando 75 a\u00f1os de excelencia - Kongskilde Industries","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Celebrando 75 a\u00f1os de excelencia","og_description":"2024 marca un hito notable para Kongskilde Industries&#8230; \u00a1nuestro 75 aniversario! En 1949, la visi\u00f3n innovadora del Sr. Petersen y el Sr. Tyndeskov allan\u00f3 el camino para la creaci\u00f3n de nuestra empresa. Desde aquel humilde comienzo en un peque\u00f1o pueblo cerca de Copenhague, hemos evolucionado hasta convertirnos en un l\u00edder [&hellip;]","og_url":"https:\/\/kongskilde-industries.com\/es\/celebrando-75-anos-de-excelencia\/","og_site_name":"Kongskilde Industries","article_publisher":"https:\/\/www.facebook.com\/kongskildegrain","article_published_time":"2024-01-08T21:41:02+00:00","article_modified_time":"2026-04-07T10:21:29+00:00","og_image":[{"width":2000,"height":1500,"url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Anniversary-Cover.jpg","type":"image\/jpeg"}],"author":"breewunderlich","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/kongskilde-industries.com\/es\/celebrando-75-anos-de-excelencia\/#article","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/celebrando-75-anos-de-excelencia\/"},"author":{"name":"breewunderlich","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb"},"headline":"Celebrando 75 a\u00f1os de excelencia","datePublished":"2024-01-08T21:41:02+00:00","dateModified":"2026-04-07T10:21:29+00:00","mainEntityOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/celebrando-75-anos-de-excelencia\/"},"wordCount":229,"publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/celebrando-75-anos-de-excelencia\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Anniversary-Cover.jpg","keywords":["Noticias"],"articleSection":["Noticias Industriales","Noticias sobre el grano"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kongskilde-industries.com\/es\/celebrando-75-anos-de-excelencia\/","url":"https:\/\/kongskilde-industries.com\/es\/celebrando-75-anos-de-excelencia\/","name":"Celebrando 75 a\u00f1os de excelencia - Kongskilde Industries","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/celebrando-75-anos-de-excelencia\/#primaryimage"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/celebrando-75-anos-de-excelencia\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Anniversary-Cover.jpg","datePublished":"2024-01-08T21:41:02+00:00","dateModified":"2026-04-07T10:21:29+00:00","breadcrumb":{"@id":"https:\/\/kongskilde-industries.com\/es\/celebrando-75-anos-de-excelencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kongskilde-industries.com\/es\/celebrando-75-anos-de-excelencia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/celebrando-75-anos-de-excelencia\/#primaryimage","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Anniversary-Cover.jpg","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/75-Anniversary-Cover.jpg","width":2000,"height":1500,"caption":"75 Kongskilde 1949 - 2024"},{"@type":"BreadcrumbList","@id":"https:\/\/kongskilde-industries.com\/es\/celebrando-75-anos-de-excelencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kongskilde-industries.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Celebrando 75 a\u00f1os de excelencia"}]},{"@type":"WebSite","@id":"https:\/\/kongskilde-industries.com\/es\/#website","url":"https:\/\/kongskilde-industries.com\/es\/","name":"Kongskilde Industries","description":"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.","publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"alternateName":"Kongskilde","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kongskilde-industries.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kongskilde-industries.com\/es\/#organization","name":"Kongskilde Industries","alternateName":"Kongskilde","url":"https:\/\/kongskilde-industries.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","width":2550,"height":392,"caption":"Kongskilde Industries"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kongskildegrain","https:\/\/www.linkedin.com\/company\/kongskilde-industries-a-s\/","https:\/\/www.youtube.com\/@kongskildeindustries"]},{"@type":"Person","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/e5a01ab01b55e978a1009059d5725fcb","name":"breewunderlich"}]}},"_links":{"self":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/comments?post=81285"}],"version-history":[{"count":1,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81285\/revisions"}],"predecessor-version":[{"id":82462,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81285\/revisions\/82462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media\/81281"}],"wp:attachment":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media?parent=81285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/categories?post=81285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/tags?post=81285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":81168,"date":"2023-11-21T14:06:33","date_gmt":"2023-11-21T14:06:33","guid":{"rendered":"https:\/\/kongskilde-industries.com\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/"},"modified":"2026-04-07T10:29:04","modified_gmt":"2026-04-07T10:29:04","slug":"kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo","status":"publish","type":"post","link":"https:\/\/kongskilde-industries.com\/es\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/","title":{"rendered":"Kongskilde en Agritechnica 2024: Un escaparate de productos probados en el tiempo"},"content":{"rendered":"\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p>\u00a1Estamos encantados de compartir el tremendo \u00e9xito y el abrumador inter\u00e9s que Kongskilde experiment\u00f3 en Agritechnica la semana pasada! Nuestro stand llam\u00f3 la atenci\u00f3n sobre nuestras soluciones de eficacia probada en la limpieza de granos y el transporte neum\u00e1tico.<\/p>\n\n\n\n<p><strong>Excelencia en el Cleaning de Grano: La limpiadora doble KDC 8000 toma el protagonismo<\/strong><\/p>\n\n\n\n<p>La estrella de nuestra exposici\u00f3n fue la limpiadora dual KDC 8000, un testimonio de precisi\u00f3n y eficacia en la limpieza de granos. Los visitantes quedaron intrigados por su doble funcionalidad. La capacidad de la KDC 8000 para optimizar el proceso de cleaning de una gran variedad de granos despert\u00f3 un gran entusiasmo entre los asistentes.<\/p>\n\n\n\n<p><strong>Transporte neum\u00e1tico: Conozca el Ventilador de Succi\u00f3n SupraVac 2000<\/strong><\/p>\n\n\n\n<p>Nuestro Ventilador de succi\u00f3n SupraVac 2000 se mantuvo en pie, demostrando una potencia sin igual en el transporte neum\u00e1tico. La SupraVac 2000 mostr\u00f3 su flexibilidad tanto en el transporte interior como exterior, dejando una impresi\u00f3n duradera en los visitantes que buscaban soluciones eficientes para la manipulaci\u00f3n de materiales.<\/p>\n\n\n\n<p>Vea un resumen del espect\u00e1culo aqu\u00ed:<\/p>\n<\/div><\/div>\n\n<div class=\"wp-block-columns is-style-xl-gutter is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Agritechnica 2023\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/KrSKPyvNII4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\"><div class=\"wp-block-image is-resized\">\n<figure class=\"alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Agritechnica_stand_web.jpg\" alt=\"\" class=\"wp-image-81156\" srcset=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Agritechnica_stand_web.jpg 1000w, https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Agritechnica_stand_web-600x450.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">La <em>limpiadora de granos doble KDC PLUS y el ventilador de aspiraci\u00f3n SupraVac <\/em>expuestos en Hannover<\/figcaption><\/figure>\n<\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nuestro stand llam\u00f3 la atenci\u00f3n sobre nuestras soluciones de eficacia probada en la limpieza de granos y el transporte neum\u00e1tico.<\/p>\n","protected":false},"author":3,"featured_media":81162,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[385],"tags":[758,301],"class_list":["post-81168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-cereales","tag-noticias","tag-supravac-es"],"acf":{"footer_cta_override":"default","remove_footer_margin":false,"footer_cta":{"background_image":null,"product_image":null,"heading":"","subheading":"","link":null,"link_secondary":null}},"featured_image_src":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Agritechnica_stand_web.jpg","author_info":{"display_name":"anneemborg","author_link":"https:\/\/kongskilde-industries.com\/es\/author\/anneemborg\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kongskilde en Agritechnica 2024: Un escaparate de productos probados en el tiempo - Kongskilde Industries<\/title>\n<meta name=\"description\" content=\"Nuestro stand llam\u00f3 la atenci\u00f3n sobre nuestras soluciones de eficacia probada en la limpieza de granos y el transporte neum\u00e1tico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kongskilde en Agritechnica 2024: Un escaparate de productos probados en el tiempo\" \/>\n<meta property=\"og:description\" content=\"Nuestro stand llam\u00f3 la atenci\u00f3n sobre nuestras soluciones de eficacia probada en la limpieza de granos y el transporte neum\u00e1tico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kongskilde-industries.com\/es\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/\" \/>\n<meta property=\"og:site_name\" content=\"Kongskilde Industries\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kongskildegrain\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-21T14:06:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T10:29:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Agritechnica_stand_web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anneemborg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\\\/\"},\"author\":{\"name\":\"anneemborg\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/17005c161883cac3a5706c17b30610f8\"},\"headline\":\"Kongskilde en Agritechnica 2024: Un escaparate de productos probados en el tiempo\",\"datePublished\":\"2023-11-21T14:06:33+00:00\",\"dateModified\":\"2026-04-07T10:29:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\\\/\"},\"wordCount\":211,\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Agritechnica_stand_web.jpg\",\"keywords\":[\"Noticias\",\"Supravac\"],\"articleSection\":[\"Noticias sobre el grano\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\\\/\",\"name\":\"Kongskilde en Agritechnica 2024: Un escaparate de productos probados en el tiempo - Kongskilde Industries\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Agritechnica_stand_web.jpg\",\"datePublished\":\"2023-11-21T14:06:33+00:00\",\"dateModified\":\"2026-04-07T10:29:04+00:00\",\"description\":\"Nuestro stand llam\u00f3 la atenci\u00f3n sobre nuestras soluciones de eficacia probada en la limpieza de granos y el transporte neum\u00e1tico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Agritechnica_stand_web.jpg\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Agritechnica_stand_web.jpg\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kongskilde en Agritechnica 2024: Un escaparate de productos probados en el tiempo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"name\":\"Kongskilde Industries\",\"description\":\"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\"},\"alternateName\":\"Kongskilde\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#organization\",\"name\":\"Kongskilde Industries\",\"alternateName\":\"Kongskilde\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"contentUrl\":\"https:\\\/\\\/kongskilde-industries.com\\\/wp-content\\\/uploads\\\/Kongskilde-logo_notag_blue.png\",\"width\":2550,\"height\":392,\"caption\":\"Kongskilde Industries\"},\"image\":{\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kongskildegrain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kongskilde-industries-a-s\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@kongskildeindustries\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kongskilde-industries.com\\\/es\\\/#\\\/schema\\\/person\\\/17005c161883cac3a5706c17b30610f8\",\"name\":\"anneemborg\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kongskilde en Agritechnica 2024: Un escaparate de productos probados en el tiempo - Kongskilde Industries","description":"Nuestro stand llam\u00f3 la atenci\u00f3n sobre nuestras soluciones de eficacia probada en la limpieza de granos y el transporte neum\u00e1tico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Kongskilde en Agritechnica 2024: Un escaparate de productos probados en el tiempo","og_description":"Nuestro stand llam\u00f3 la atenci\u00f3n sobre nuestras soluciones de eficacia probada en la limpieza de granos y el transporte neum\u00e1tico.","og_url":"https:\/\/kongskilde-industries.com\/es\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/","og_site_name":"Kongskilde Industries","article_publisher":"https:\/\/www.facebook.com\/kongskildegrain","article_published_time":"2023-11-21T14:06:33+00:00","article_modified_time":"2026-04-07T10:29:04+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Agritechnica_stand_web.jpg","type":"image\/jpeg"}],"author":"anneemborg","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/#article","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/"},"author":{"name":"anneemborg","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/17005c161883cac3a5706c17b30610f8"},"headline":"Kongskilde en Agritechnica 2024: Un escaparate de productos probados en el tiempo","datePublished":"2023-11-21T14:06:33+00:00","dateModified":"2026-04-07T10:29:04+00:00","mainEntityOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/"},"wordCount":211,"publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Agritechnica_stand_web.jpg","keywords":["Noticias","Supravac"],"articleSection":["Noticias sobre el grano"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/","url":"https:\/\/kongskilde-industries.com\/es\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/","name":"Kongskilde en Agritechnica 2024: Un escaparate de productos probados en el tiempo - Kongskilde Industries","isPartOf":{"@id":"https:\/\/kongskilde-industries.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/#primaryimage"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/#primaryimage"},"thumbnailUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Agritechnica_stand_web.jpg","datePublished":"2023-11-21T14:06:33+00:00","dateModified":"2026-04-07T10:29:04+00:00","description":"Nuestro stand llam\u00f3 la atenci\u00f3n sobre nuestras soluciones de eficacia probada en la limpieza de granos y el transporte neum\u00e1tico.","breadcrumb":{"@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kongskilde-industries.com\/es\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/#primaryimage","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Agritechnica_stand_web.jpg","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Agritechnica_stand_web.jpg","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/kongskilde-industries.com\/es\/kongskilde-at-agritechnica-2024-una-muestra-de-productos-probados-en-el-tiempo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kongskilde-industries.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Kongskilde en Agritechnica 2024: Un escaparate de productos probados en el tiempo"}]},{"@type":"WebSite","@id":"https:\/\/kongskilde-industries.com\/es\/#website","url":"https:\/\/kongskilde-industries.com\/es\/","name":"Kongskilde Industries","description":"Los sistemas Kongskilde son una soluci\u00f3n flexible y potente tanto para aplicaciones industriales como para cereales.","publisher":{"@id":"https:\/\/kongskilde-industries.com\/es\/#organization"},"alternateName":"Kongskilde","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kongskilde-industries.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kongskilde-industries.com\/es\/#organization","name":"Kongskilde Industries","alternateName":"Kongskilde","url":"https:\/\/kongskilde-industries.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","contentUrl":"https:\/\/kongskilde-industries.com\/wp-content\/uploads\/Kongskilde-logo_notag_blue.png","width":2550,"height":392,"caption":"Kongskilde Industries"},"image":{"@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kongskildegrain","https:\/\/www.linkedin.com\/company\/kongskilde-industries-a-s\/","https:\/\/www.youtube.com\/@kongskildeindustries"]},{"@type":"Person","@id":"https:\/\/kongskilde-industries.com\/es\/#\/schema\/person\/17005c161883cac3a5706c17b30610f8","name":"anneemborg"}]}},"_links":{"self":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/comments?post=81168"}],"version-history":[{"count":2,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81168\/revisions"}],"predecessor-version":[{"id":82751,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/posts\/81168\/revisions\/82751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media\/81162"}],"wp:attachment":[{"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/media?parent=81168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/categories?post=81168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kongskilde-industries.com\/es\/wp-json\/wp\/v2\/tags?post=81168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}]